{"id":130997,"date":"2020-06-03T16:46:36","date_gmt":"2020-06-03T14:46:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/conte-modernizzare-e-digitalizzare-il-paese-il-ponte-sullo-stretto-valuteremo\/"},"modified":"2023-01-16T18:00:10","modified_gmt":"2023-01-16T17:00:10","slug":"356895-conte-modernizzare-e-digitalizzare-il-paese-il-ponte-sullo-stretto-valuteremo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/356895-conte-modernizzare-e-digitalizzare-il-paese-il-ponte-sullo-stretto-valuteremo\/","title":{"rendered":"Conte &#8220;modernizzare e digitalizzare il Paese. Il ponte sullo Stretto? Valuteremo&#8221;"},"content":{"rendered":"<h4>Discorso del premier Conte all&#8217;Italia nel giorno della riapertura di tutte le regioni &#8220;Il trend dei nuovi casi diagnosticati diagnosticati \u00e8 in costante diminuzione. Giusto tornare a sorridere e a vivere le citt\u00e0 ma dico facciamo attenzione. Q<strong>uando ci saranno i progetti, senza pregiudizi mi sieder\u00f2 a un tavolo e valuter\u00f2 anche il Ponte sullo Stretto<\/strong> <!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; La conferenza stampa del Premiere Conte nel giorno in cui si riapre alla mobilit\u00e0 tra le Regioni non pu\u00f2 che partire dai dai del contagio delle ultime settimane &#8220;Da oggi\u00a0 &#8211; spiga Conte &#8211; apriamo i nostri confini regionali. Questo significa che <strong>possiamo spostarsi da regione a regione senza pi\u00f9 autocertificazione<\/strong>. Una decisione presa con consapevolezza perch\u00e9 i dati della curva epimeiologica ci dicono che i<strong>l sistema di controllo che abbiamo adottato sta funzionando<\/strong> cos\u00ec come il nostro indirizzo politico di procedere sulla base di riaperture progressive, in base ad un costante monitoraggi. A distanza di un mese dal 4 maggio, giorno delle prime riaperture, possiamo dire, seppur con la massima prudenza ma anche in modo chiaro,<strong> i numeri sono incoraggianti<\/strong>. Gli ultimi monitoraggi non segnalano situazione critiche e non ci sono situazioni di sovraccarico delle strutture ospedaliere in tutta Italia. <b>Il trend dei nuovi casi diagnosticati diagnosticati \u00e8 in costante diminuzione in tutto il Paese<\/b>, dalla Lombardia alla Sicilia&#8221;.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2FGiuseppeConte64%2Fvideos%2F259342315125817%2F&amp;show_text=0&amp;width=560\" width=\"560\" height=\"315\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&#8220;Questo ci conforta e dimostra &#8211; ha aggiunto Conte &#8211; che la strategia adottata passo dopo passo \u00e8 stata ed \u00e8 quella giusta. Ci da fiducia in vista delle decisioni che saremo chiamati ad adottare\u00a0 delle prossime settimane. Ci siamo inoltrati nella bella stagione, in giro nelle strade e nelle nostre piazze c&#8217;\u00e8 grande attenzione per la socialit\u00e0 ritrovata. Giusto, giustissimo, <strong>ci meritiamo il sorriso e l&#8217;allegria dopo settimane di duro sacrificio<\/strong>. Ma \u00e8 bene ricordare sempre che se ci ritroviamo ora in queste condizioni e siamo tra i primi Paesi europei che possono riavviare tutte le attivit\u00e0 in condizioni i sicurezza \u00e8 perch\u00e9 a<strong>bbiamo accettato tutti insieme di compiere dei sacrifici, di essere responsabili<\/strong> e modificare le nostre abitudini di vita. <strong>Dico solo facciamo attenzione<\/strong>, le uniche misure ad oggi efficaci a cui affidiamo l&#8217;opera di contrasto della diffusione del virus sono il distanziamento e l&#8217;uso delle mascherine dove sia necessario. Abbandonare queste precauzioni perch\u00e9 pensiamo che oggi il virus sia scomparso \u00e8 una grave leggerezza, completamente smentita dal numero dei contagi che seppur in calo continuano ad essere registrati quotidianamente&#8221;.<\/p>\n<p>Il Premiere poi parla tocca il tema caldo dell&#8217;economia e del rilancio dell&#8217;Italia a partire dal Sud che &#8220;<strong>avr\u00e0 una attenzione privilegiata<\/strong>. Con il ministro Provenzano stiamo lavorando ad una <strong>fiscalit\u00e0 di vantaggio per l&#8217;intero Meridione<\/strong>. Se riusciamo a coniugare una fiscalit\u00e0 di vantaggio con gli investimenti programmati possiamo rendere attrattivo davvero il nostro Sud<strong>. Occorre una seria riforma fiscale. Il nostro fisco \u00e8 iniquo e inefficiente e su questo stiamo lavorando&#8221;<\/strong>, ha detto il premier, &#8220;l&#8217;ultima riforma fiscale \u00e8 di cinquanta anni fa: serve una reale progressivit\u00e0 coniugando lotta al sommerso per restituire risorse a tutti i contribuenti. Sicuramente ci<strong> metteremo nella condizione di fare pagare tutti e tutti meno.<\/strong>\u00a0<strong>Dobbiamo modernizzare e rilanciare il Paese<\/strong> puntando sulla digitalizzazione e sull&#8217;innovazione. Dobbiamo<strong> lavorare per sostenere le nostre imprese grandi e piccole che siano<\/strong>. Occorre rilanciare gli investimenti pubblici e privati tagliando la burocrazia. Questa crisi deve essere un&#8217;occasione per superare i problemi strutturali e ridisegnare il Paese &#8211; ha proseguito\u00a0 &#8211; a cominciare dal miglioramento della rete ferroviaria, perch\u00e8 attualmente la rete che abbiamo \u00e8 inaccettabile. Oggi \u00e8 partito per la prima volta il Frecciarossa da Torino a Reggio Calabria.<strong> Dobbiamo assolutamente lavorare sull&#8217;alta velocit\u00e0. <\/strong>Poi Conte a specifica domanda ha annunciato: &#8220;<strong>quando ci saranno i progetti, senza pregiudizi mi sieder\u00f2 a un tavolo e valuter\u00f2 anche il Ponte sullo Stretto<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discorso del premier Conte all&#8217;Italia nel giorno della riapertura di tutte le regioni &#8220;Il trend dei nuovi casi diagnosticati diagnosticati \u00e8 in costante diminuzione. Giusto tornare a sorridere e a vivere le citt\u00e0 ma dico facciamo attenzione. Quando ci saranno i progetti, senza pregiudizi mi sieder\u00f2 a un tavolo e valuter\u00f2 anche il Ponte sullo [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":130998,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-130997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130997"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130998"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}