{"id":131081,"date":"2020-06-04T16:03:40","date_gmt":"2020-06-04T14:03:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-domani-e-sabato-screening-volontario-con-test-rapido-sul-coronavirus\/"},"modified":"2023-01-16T18:00:15","modified_gmt":"2023-01-16T17:00:15","slug":"357116-cosenza-domani-e-sabato-screening-volontario-con-test-rapido-sul-coronavirus","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/357116-cosenza-domani-e-sabato-screening-volontario-con-test-rapido-sul-coronavirus\/","title":{"rendered":"Cosenza, domani e sabato screening volontario con test rapido sul coronavirus"},"content":{"rendered":"<h4>Venerd\u00ec 5 giugno in piazza dei Bruzi e sabato 6 giugno sull&#8217;isola pedonale di Corso Mazzini, i cittadini potranno sottoporsi volontariamente ad uno screening per l&#8217;accertamento del contagio da Covid-19 attraverso l&#8217;utilizzo di test rapidi IGG\/IGM.<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\nCOSENZA\u00a0 &#8211; <strong>Venerd\u00ec 5 giugno in Piazza dei Bruzi e sabato 6 giugno sull&#8217;isola pedonale di Corso Mazzini<\/strong>, tutti i cittadini che lo vorranno, potranno sottoporsi a partire dalle ore 8,30 (per tutte le due giornate previste) ad <strong>uno screening volontario per l&#8217;accertamento del contagio da Covid-19, attraverso l&#8217;utilizzo di test rapidi IGG\/IGM.<\/strong> Lo screening \u00e8 a cura della cooperativa sociale ADIS Cosenza onlus che lo ha proposto al Comune di Cosenza e che lo eseguir\u00e0 attraverso personale medico e infermieristico. L&#8217;iniziativa si inquadra nell&#8217;ambito della campagna relativa allo screening di massa Covid-19, promossa dalla ADIS COSENZA ONLUS e volta a contenere la diffusione del virus.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10454\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-357131\" src=\"https:\/\/quicosenza.it\/news\/10454\" alt=\"\" width=\"548\" height=\"460\" title=\"\"><\/a><\/p>\n<h4>Postazioni con ambulanza e costo del test<\/h4>\n<p>Lo screening avr\u00e0 dunque inizio domani venerd\u00ec 5 giugno, in Piazza dei Bruzi dove soster\u00e0 un&#8217;ambulanza per l&#8217;effettuazione dei test. Sabato 6 giugno si sposter\u00e0 poi sull&#8217;isola pedonale. Sono <strong>tre le postazioni con ambulanza<\/strong> individuate su Corso Mazzini: la prima nei pressi dell&#8217;<strong>incrocio con Via Piave<\/strong>, la seconda in<strong> Piazza 11 settembre<\/strong> e la terza alla <strong>Salita \u201cPagliaro\u201d<\/strong>. Il test, denominato<strong> \u201cpungidito\u201d,<\/strong> necessita di una goccia di sangue prelevata direttamente dal dito del paziente. <strong>I risultati saranno letti in circa 10 minuti<\/strong>. I test Covid19-IgG\/IgM che saranno utilizzati sono regolarmente registrati presso il Ministero della Salute.<\/p>\n<p>La specificit\u00e0 del test \u00e8 pari a 99,5% per le IGG e 99,2% per Igm. La sensibilit\u00e0 \u00e8 pari al 100% per le IGG e al 91,8% per IGM. L\u2019accuratezza \u00e8 pari al 99,6% per le IGG e 97,8% per Igm. <strong>Il contributo a carico di ogni persona che intender\u00e0 sottoporsi allo screening volontario \u00e8 pari al costo convenzionato di 25,00 euro<\/strong>. Il personale medico e infermieristico sar\u00e0 responsabile della corretta effettuazione del test, eseguendo il trattamento e la relativa refertazione in conformit\u00e0 delle normative nazionali sulla privacy e sulla tutela dei dati sensibili. Nel caso in cui si dovessero riscontrare delle persone positive al test, la Cooperativa ADIS COSENZA ONLUS attiver\u00e0 tutte le procedure previste dalla legge. <strong>E\u2019 necessario procedere alla prenotazione del test chiamando il numero 346\/2264351.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 5 giugno in piazza dei Bruzi e sabato 6 giugno sull&#8217;isola pedonale di Corso Mazzini, i cittadini potranno sottoporsi volontariamente ad uno screening per l&#8217;accertamento del contagio da Covid-19 attraverso l&#8217;utilizzo di test rapidi IGG\/IGM.<\/p>\n","protected":false},"author":55,"featured_media":131082,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[681],"class_list":["post-131081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=131081"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/131082"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=131081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=131081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=131081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}