{"id":131095,"date":"2020-06-05T10:17:06","date_gmt":"2020-06-05T08:17:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-dolce-erika-e-stata-restituita-blu-torna-ad-abbracciare-la-famiglia-dopo-il-covid\/"},"modified":"2023-01-16T18:00:16","modified_gmt":"2023-01-16T17:00:16","slug":"357159-la-dolce-erika-e-stata-restituita-blu-torna-ad-abbracciare-la-famiglia-dopo-il-covid","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/357159-la-dolce-erika-e-stata-restituita-blu-torna-ad-abbracciare-la-famiglia-dopo-il-covid\/","title":{"rendered":"La dolce Erika \u00e8 stata &#8220;restituita&#8221;. Blu torna ad abbracciare la famiglia dopo il Covid"},"content":{"rendered":"<h4>Questa settimana parte l&#8217;appello per Erika, che era stata adottata ma poi purtroppo restituita. Inoltre, raccontiamo la storia di Blu, il pastore tedesco che dopo oltre un mese ha ritrovato la sua famiglia<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<h3>Erika<\/h3>\n<p>Aveva poco pi\u00f9 di un anno quando ha varcato il cancello del canile per lasciarlo definitivamente. Dopo mesi dietro le sbarre del box era stata scelta e adottata. Timida e dolce aveva trovato una famiglia che per\u00f2, dopo alcuni mesi l&#8217;ha &#8216;restituita&#8217;. Nonostante il tentativo di trovare una soluzione con chi l&#8217;aveva adottata le volontarie, una domenica, sono andate a prenderla. Con il suo musetto era affacciata ad un balconcino, adagiata su un materassino da mare con accanto un piattino con dell&#8217;acqua e una manciata di croccantini.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-357197 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/06\/erika-2.jpg\" alt=\"\" width=\"379\" height=\"722\" title=\"\"><\/p>\n<p>Visibilmente denutrita e ancora pi\u00f9 timida di come era quando \u00e8 entrata in canile, Erika aveva gli occhi della solitudine che era costretta a vivere. Le volontarie non se la sono sentita di riportarla in canile e per questo Erika ora, \u00e8 in pensione. Ma ha bisogno di una casa stabile, di una famiglia che le voglia bene, di compagnia e di amore.<\/p>\n<p>Erika \u00e8 a Cosenza e si affida vaccinata, microchippata e sterilizzata. Nata a fine 2017 ha circa tre anni, ed \u00e8 una taglia medio contenuta (circa 13\/14 kg). Compatibile con i suoi simili, sia maschi che femmine. Adottabile in zona e in tutto il centro nord Italia previo modulo conoscitivo e colloquio preaffido. Seguiranno poi controlli post affido.<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA la rubrica di questa settimana<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/834547189&amp;color=%23ff5500&amp;auto_play=true&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<div style=\"font-size: 10px; color: #cccccc; line-break: anywhere; word-break: normal; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif; font-weight: 100;\"><a style=\"color: #cccccc; text-decoration: none;\" title=\"QuiCosenza.it\" href=\"https:\/\/quicosenza.it\/news\/10087\" target=\"_blank\" rel=\"noopener noreferrer\">QuiCosenza.it<\/a> \u00b7 <a style=\"color: #cccccc; text-decoration: none;\" title=\"Qui La Zampa - Erika\" href=\"https:\/\/quicosenza.it\/news\/10455\" target=\"_blank\" rel=\"noopener noreferrer\">Qui La Zampa &#8211; Erika<\/a><\/div>\n<p>&nbsp;<\/p>\n<h3>Blu, le commoventi immagini del pastore che riabbraccia i padroni dopo il Covid<\/h3>\n<p>I volontari della Leidaa, Lega italiana per la Difesa degli Animali e dell\u2019Ambiente, hanno accudito Blu per tutto il tempo della ripresa della sua famiglia. L&#8217;incontro \u00e8 stato meraviglioso. Dopo la sofferenza di una lunga separazione, il pastore tedesco Blu di Lainate, \u00e8 stato il primo degli animali presi in carico dall\u2019associazione Leidaa a tornare a casa.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cDopo 37 giorni in cui \u00e8 stato accudito amorevolmente, il cagnolone ha potuto rivedere i suoi proprietari, che avevano chiamato il nostro servizio, un giorno prima di essere ricoverati d\u2019urgenza \u2013 spiegano dall\u2019associazione \u2013 Blu era molto triste nel doverli lasciare: dopo un lungo abbraccio i nostri volontari lo hanno preso in cura con amore, come fosse il loro cane, e gli hanno dedicato tutte le attenzioni possibili. Ai proprietari ricoverati mandavano quasi ogni giorno foto e video di Blu. Il ritorno a casa \u00e8 stato un vero \u201cfuoco di gioia\u201d, un evento carico di emozioni, come si vede nel filmato\u201d.<\/p>\n<p>https:\/\/www.facebook.com\/AssociazioneLEIDAA\/videos\/673052353550297\/<\/p>\n<p>\u201cSiamo stremati ma felici \u2013 spiega l\u2019onorevole lecchese Michela Vittoria Brambilla \u2013 Stremati, al limite delle nostre forze, per il gran lavoro di questi mesi. Felici di aver salvato tanti animali che avrebbero corso grossissimi rischi, felici di aver trovato una nuova casa per quelli che hanno perduto la loro famiglia, ancor pi\u00f9 felici di aver restituito gli amici a quattrozampe ai proprietari che hanno vinto la battaglia con il Covid-19. Vedere la gioia delle persone e degli animali nel momento della riunione ripaga di tanti sforzi compiuti gratuitamente e in spirito di servizio per aiutare gli altri. Questo fa una grande assicurazione, questo fanno persone di grande cuore come i volontari animalisti\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-357196 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/06\/Blu-covid-19.jpg\" alt=\"\" width=\"538\" height=\"890\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Se vuoi scriverci per chiedere informazioni sui cani da adottare: <strong>redazione@quicosenza.it<\/strong> (nell\u2019oggetto indicare \u201c<strong>Qui la Zampa<\/strong>\u201c); Se invece vuoi adottare i cani, il giorno delle adozioni in canile a <strong>Donnici<\/strong> \u00e8 il<span style=\"color: #ff0000;\"><strong>\u00a0GIOVEDI&#8217;<\/strong><\/span>. Le adozioni al canile sanitario in contrada Acquafredda di <strong>Mendicino<\/strong> (Cs) invece, si possono effettuare di <span style=\"color: #ff0000;\"><strong>LUNED\u00cc<\/strong> <\/span>dalle 9:30 alle 12:30<\/p>\n<h3 style=\"text-align: center;\">Numeri utili per informazioni e\/o adozioni<\/h3>\n<p style=\"text-align: center;\">Letizia 327 636 2179<br \/>\nMaria Giulia 334 354 2780<br \/>\nTeresa 348 134 3975<br \/>\nNadia 389 051 7756<br \/>\nMaria Francesca 3917348381<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5314\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0LEGGI TUTTI GLI ARTICOLI della rubrica &#8220;Qui la Zampa&#8221;<\/a><\/span><\/h4>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa settimana parte l&#8217;appello per Erika, che era stata adottata ma poi purtroppo restituita. Inoltre, raccontiamo la storia di Blu, il pastore tedesco che dopo oltre un mese ha ritrovato la sua famiglia<\/p>\n","protected":false},"author":42,"featured_media":131096,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[47],"tags":[],"class_list":["post-131095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qui-la-zampa"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=131095"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/131096"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=131095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=131095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=131095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}