{"id":131472,"date":"2020-06-11T13:57:28","date_gmt":"2020-06-11T11:57:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-fiume-lao-da-domani-ritorna-ad-accogliere-i-turisti\/"},"modified":"2023-01-16T18:00:42","modified_gmt":"2023-01-16T17:00:42","slug":"358129-il-fiume-lao-da-domani-ritorna-ad-accogliere-i-turisti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/358129-il-fiume-lao-da-domani-ritorna-ad-accogliere-i-turisti\/","title":{"rendered":"Il fiume Lao da domani ritorna ad accogliere i turisti"},"content":{"rendered":"<h4>La pratica sportiva del rafting domani rientra nella piena operativit\u00e0 grazie ai protocolli di sicurezza messi in campo da LaoRafting<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LAINO BORGO (CS) &#8211; Si torna in acqua, tra le rapide del fiume Lao, a godere dell&#8217;adrenalina che regala una discesa in gommone. <strong>Il canyon navigabile tra i pi\u00f9 suggestivi d&#8217;Europa, inserito contesto naturale del Parco Nazionale del Pollino<\/strong>, dal 2015 riconosciuto nella rete internazionale Global Geoparks Network, \u00e8 pronto ad accogliere turisti ed amanti dello sport outdoor. Dopo un lungo lavoro di preparazione, seguendo i protocolli di sicurezza nazionali forniti dalla Federazione Italia Rafting, <strong>la LaoRafting, coordinata da Andrea D&#8217;Onofrio aprir\u00e0 le porte del campo<\/strong> base domani, venerd\u00ec 12 giugno per dare il via ad una stagione di ripartenza delle attivit\u00e0 sul fiume bloccate (rispetto alla regolare riapertura di pasqua) dall&#8217;emergenza sanitaria da Coronavirus.<\/p>\n<p>\u00abOra siamo pronti e felici di poter dire che <strong>il Lao \u00e8 navigabile in tutta sicurezza.<\/strong> Ci siamo preparati con grande scrupolo ed attenzione ai particolari e <strong>siamo felici di riportare i turistici ad ammirare una delle meraviglie incontaminate del Parco nazionale pi\u00f9 grande d&#8217;Italia<\/strong>, tra natura suggestiva e biodiversit\u00e0 unica al mondo\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-358134 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/06\/LAO_RAFTING_3.jpg\" alt=\"\" width=\"750\" height=\"500\" title=\"\"><\/p>\n<p>Ventisei chilometri di adrenalina pura a stretto contatto con il fiume e l&#8217;ambiente naturale che lo circonda con una proposta per tutta la famiglia che parte da<strong> un percorso &#8220;soft&#8221; di 4 chilometri, passando per la proposta &#8220;Canyon&#8221; con la navigazione delle gole del Lao per ben 16 km, fino alle scelte &#8220;Stop &amp; Go&#8221; di 20 km<\/strong> con pranzo incluso a base di prodotti tipici all&#8217;interno di una delle basi di Laino Borgo e &#8220;Full day&#8221; che permette rimanere per un giorno interno immersi nei 26km di fiume da ammirare in tutta la sua potente bellezza con pranzo previsto <strong>all&#8217;interno dell&#8217;area turistica attrezzata Lao River Camp in localit\u00e0 Campicello<\/strong> nel territorio comunale di Laino Castello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-358132 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/06\/LAO_RAFTING_5.jpg\" alt=\"\" width=\"750\" height=\"500\" title=\"\"><\/p>\n<p>Dall&#8217;area di vestizione e acquisizione delle attrezzature, al trasferimento nell&#8217;area di imbarco, dalle posizioni sul gommone, fino allo sbarco <strong>tutto \u00e8 stato ripensato e coordinato da percorsi e protocolli utili a vivere in piena sicurezza anti contagio<\/strong> l&#8217;attivit\u00e0 all&#8217;aperto e trascorrere una giornata godendo della natura incontaminata di una delle valli pi\u00f9 suggestive paesaggisticamente del Parco del Pollino.<strong> Guide altamente qualificate accompagneranno in una spettacolare discesa lungo le rapide del fiume Lao<\/strong>, tra natura selvaggia ed incontaminata, per un&#8217;esperienza unica e alla portata di tutti e per tutte le et\u00e0.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-358130 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/06\/LAO_RAFTING_2.jpg\" alt=\"\" width=\"750\" height=\"500\" title=\"\"><\/p>\n<p>Una proposta a tutto tondo che coinvolge l&#8217;intero territorio grazie al rifugio La Principessa in localit\u00e0 <strong>Campotenese nel Comune di Morano Calabro presso il quale si potr\u00e0 godere anche di altre attivit\u00e0 esperienziali<\/strong> che propongono un contatto diretto con la natura: il trekking, le passeggiate in mountain bike, la ristorazione con l&#8217;attenzione alla valorizzazione dell&#8217;agroalimentare del territorio, senza dimenticare<strong> le discese in canoa e il canyoning<\/strong> come variabile per un primo approccio all&#8217;acqua del fiume Lao.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-358131 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/06\/LAO_RAFTING_4.jpg\" alt=\"\" width=\"750\" height=\"500\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pratica sportiva del rafting domani rientra nella piena operativit\u00e0 grazie ai protocolli di sicurezza messi in campo da LaoRafting<\/p>\n","protected":false},"author":22,"featured_media":131473,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,569],"tags":[],"class_list":["post-131472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-turismo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=131472"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/131473"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=131472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=131472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=131472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}