{"id":131514,"date":"2020-06-12T07:10:11","date_gmt":"2020-06-12T05:10:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/auto-usate-per-i-funerali-del-boss-sequestrate-dalla-guardia-di-finanza\/"},"modified":"2023-01-16T18:00:45","modified_gmt":"2023-01-16T17:00:45","slug":"358230-auto-usate-per-i-funerali-del-boss-sequestrate-dalla-guardia-di-finanza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/358230-auto-usate-per-i-funerali-del-boss-sequestrate-dalla-guardia-di-finanza\/","title":{"rendered":"Auto usate per i funerali del boss sequestrate dalla Guardia di Finanza"},"content":{"rendered":"<h4>I mezzi funebri erano stati utilizzati da un&#8217;impresa vibonese per il funerale di Salvatore Mancuso, alias &#8220;U Zoppu&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>VIBO VALENTIA &#8211; La guardia di finanza di Vibo ha sequestrato due auto utilizzate per i funerali di Salvatore Mancuso, 46 anni, ritenuto il boss dell\u2019omonima famiglia di &#8216;ndrangheta di Limbadi. I funerali vennero celebrati il 24 novembre del 2018. Dalle indagini \u00e8 emerso che il mezzo che avrebbe trasportato il <strong>feretro di Mancuso verso la chiesa di San Pantaleone<\/strong> a Limbadi non riportava alcuna insegna pubblicitaria che consentisse di risalire all\u2019impresa incaricata del funerale. E&#8217; stato scoperto che l&#8217;impresa inoltre, utilizz\u00f2 una seconda vettura ma per entrambe la societ\u00e0 funebre, non aveva pi\u00f9 il possesso di leasing. La ditta locataria, nonostante la risoluzione dei contratti per il mancato versamento dei canoni dovuti, non aveva provveduto a restituirli. Gli amministratori dell&#8217;agenzia funebre sono stati denunciati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I mezzi funebri erano stati utilizzati da un&#8217;impresa vibonese per il funerale di Salvatore Mancuso, alias &#8220;U Zoppu&#8221;<\/p>\n","protected":false},"author":42,"featured_media":131515,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-131514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=131514"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/131515"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=131514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=131514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=131514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}