{"id":131591,"date":"2020-06-13T05:49:45","date_gmt":"2020-06-13T03:49:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/regioni-le-commissioni-tutte-al-centrodestra-e-lopposizione-non-vota\/"},"modified":"2023-01-16T18:00:50","modified_gmt":"2023-01-16T17:00:50","slug":"358419-regioni-le-commissioni-tutte-al-centrodestra-e-lopposizione-non-vota","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/358419-regioni-le-commissioni-tutte-al-centrodestra-e-lopposizione-non-vota\/","title":{"rendered":"Regioni, le Commissioni tutte al centrodestra e l&#8217;opposizione non vota"},"content":{"rendered":"<h4>Un fatto inedito nella storia del Consiglio regionale calabrese. Ci sono volute 8 ore per mettersi d&#8217;accordo sulle Commissioni consiliari permanenti e sulle due Commissioni speciali<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Nuova bufera in Consiglio regionale ieri, previsto per mezzogiorno e slittato di ben otto ore tanto che la minoranza ha abbandonato la seduta per protestare contro il notevole ritardo. Il Consiglio regionale ha eletto presidenti, vice presidenti e segretari delle sei Commissioni consiliari permanenti e delle due Commissioni speciali. Un ritardo per il quale Sinibaldo Esposito (Casa delle Libert\u00e0) ha chiesto scusa ai calabresi &#8220;<strong>necessario per definire &#8211; ha spiegato &#8211; il quadro degli incarichi da ricoprire&#8221;<\/strong>.<\/p>\n<p>Il centrodestra dunque fa incetta di Commissioni e la maggioranza che sostiene Jole Santelli apre di fatto una spaccatura profonda con le opposizioni di centrosinistra, che alla fine hanno deciso di disertare l&#8217;aula e la votazione finale. Ma il centrodestra ha comunque chiuso i giochi prendendosi le Commissioni ed il Consiglio regionale si \u00e8 aggiornato rinviando le altre pratiche all&#8217;ordine del giorno alla prossima seduta.<\/p>\n<p><strong>Prima Commissione<\/strong><br \/>\nPietro Raso (Lega) \u00e8 il presidente della prima commissione \u201cAffari generali e istituzionali\u201d del Consiglio regionale. Raso \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 19 voti. Vicepresidente della prima Commissione \u00e8 il consigliere regionale del Pd, Domenico Bevacqua (un voto), mentre il segretario \u00e8 il consigliere regionale della Casa delle libert\u00e0 Giuseppe Crin\u00f2 (19). In sula non sono presenti i consiglieri di opposizione.<\/p>\n<p><strong>Seconda Commissione<\/strong><br \/>\nGiuseppe Neri (Fratelli d&#8217;Italia) \u00e8 il presidente della prima commissione \u201cBilancio, Programmazione economica e attivit\u00e0 produttive, affari dell\u2019Unione europea e relazioni con l\u2019estero\u201d del Consiglio regionale. Neri \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 19 voti. Anche a questa votazione non hanno partecipato i gruppi di opposizione, non entrati in aula per protesta contro la maggioranza. Vicepresidente della seconda Commissione \u00e8 il consigliere regionale dei Democratici progressisti, Flora Sculco (un voto), mentre il segretario \u00e8 il consigliere regionale dell&#8217;Udc, Nicola Paris (20).<\/p>\n<p><strong>Terza Commissione<\/strong><br \/>\nBaldo Esposito (Casa delle Libert\u00e0) \u00e8 il presidente della terza commissione \u201cSanit\u00e0, attivit\u00e0 sociali culturali e formative\u201d del Consiglio regionale. Esposito \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 19 voti. Anche a questa votazione non hanno partecipato i gruppi di opposizione, non entrati in aula per protesta contro la maggioranza. Vicepresidente della terza Commissione \u00e8 il consigliere regionale del Pd Libero Notarangelo (un voto), mentre il segretario \u00e8 il consigliere regionale di Fratelli d&#8217;Italia Raffaele Sainato (20 voti).<\/p>\n<p><strong>Quarta Commissione<\/strong><br \/>\nPierluigi Caputo (Jole Santelli Presidente) \u00e8 il presidente della quarta commissione \u201cAssetto e utilizzazione del territorio, protezione dell\u2019ambiente\u201d del Consiglio regionale. Caputo \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 19 voti. Anche a questa votazione non hanno partecipato i gruppi di opposizione, non entrati in aula per protesta contro la maggioranza. Vicepresidente della terza Commissione \u00e8 il consigliere regionale del Pd Carlo Guccione (un voto), mentre il segretario \u00e8 il consigliere regionale della Lega Piero Raso (19 voti).<\/p>\n<p><strong>Quinta Commissione<\/strong><br \/>\nRaffaele Sainato (Fratelli d&#8217;Italia) \u00e8 il presidente della quinta commissione \u201cRiforme\u201d del Consiglio regionale. Sainato \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 18 voti. Anche a questa votazione non hanno partecipato i gruppi di opposizione, non entrati in aula per protesta contro la maggioranza. Vicepresidente della quinta Commissione \u00e8 il consigliere regionale del Gruppo Misto Francesco Pitaro (un voto), mentre il segretario \u00e8 il consigliere regionale di Forza Italia Giovanni Arruzzolo (19 voti).<\/p>\n<p><strong>Sesta Commissione<\/strong><br \/>\nPietro Molinaro (Lega) \u00e8 il presidente della sesta commissione \u201cAgricoltura e foreste, Consorzi di bonifica, Turismo, Commercio, Risorse naturali, Sport e Politiche giovanili\u201d del Consiglio regionale. Molinaro \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 19 voti. Anche a questa votazione non hanno partecipato i gruppi di opposizione, non entrati in aula per protesta contro la maggioranza. Vicepresidente della sesta Commissione \u00e8 il consigliere regionale del Pd Luigi Tassone (un voto), mentre il segretario \u00e8 il consigliere regionale di Forza Italia Domenico Giannetta (20 voti).<\/p>\n<p><strong>Commissione Vigilanza<\/strong><br \/>\nDomenico Giannetta (Forza Italia) \u00e8 il presidente della \u201cCommissione speciale di Vigilanza\u201d del Consiglio regionale. Giannetta \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 19 voti. Anche a questa votazione non hanno partecipato i gruppi di opposizione, non entrati in aula per protesta contro la maggioranza. Vicepresidente della Commissione Vigilanza \u00e8 il consigliere regionale di \u201cIo Resto in Calabria\u201d Pippo Callipo (un voto), mentre il segretario \u00e8 il consigliere regionale di \u201cJole Santelli Presidente\u201d Pierluigi Caputo (19 voti).<\/p>\n<p><strong>Commissione Anti &#8216;ndrangheta<\/strong><br \/>\nAntonio De Caprio (Forza Italia) \u00e8 il presidente della \u201cCommissione consiliare contro il fenomeno della \u2018ndrangheta, della corruzione e dell\u2019illegalit\u00e0 diffusa\u201d del Consiglio regionale. De Caprio \u00e8 stato eletto stasera nella seduta del Consiglio regionale con 19 voti. Anche a questa votazione non hanno partecipato i gruppi di opposizione, non entrati in aula per protesta contro la maggioranza. Vicepresidente della Commissione Anti-&#8216;ndrangheta \u00e8 il consigliere regionale dei Democratici Progressisti Giuseppe Aieta (un voto), mentre il segretario \u00e8 il consigliere regionale della Lega Tilde Minasi (19 voti).<\/p>\n<h4>I consiglieri regionali di \u201cIo resto in Calabria\u201d abbandonano Palazzo Campanella<\/h4>\n<p>Hanno manifestato la loro \u00abindignazione per lo stallo totale in cui il centrodestra ha fatto piombare la massima Assemblea legislativa calabrese\u00bb. In una nota congiunta Pippo Callipo (che non era presente a Reggio per motivi di salute), Graziano Di Natale e Marcello Anastasi definiscono \u00ab<strong>inaccettabile la situazione che si \u00e8 venuta a creare in Consiglio regionale:<\/strong> il centrodestra ha impedito per oltre otto ore di avviare la seduta, convocata per le 12, perch\u00e9 non riesce ancora a trovare la quadra sulle poltrone di presidente delle Commissioni. Come se non fosse gi\u00e0 abbastanza grave aver creato una nuova Commissione che, come abbiamo denunciato per primi, coster\u00e0 500 mila euro in 5 anni, il centrodestra \u2013 proseguono Callipo, Di Natale e Anastasi \u2013 non riusciva a mettersi d\u2019accordo nemmeno per la guida di un organismo importante dal punto di vista simbolico come la Commissione Antindrangheta. Non intendiamo prestarci ad accordi sottobanco e ad inciuci di alcun tipo solo perch\u00e9 chi ha vinto le elezioni non \u00e8 capace nemmeno di far insediare gli organismi essenziali per il funzionamento del Consiglio regionale. Non siamo e non saremo in vendita e non accetteremo mai di barattare la nostra dignit\u00e0 politica con prebende di alcun tipo. Se il centrodestra \u2013 concludono Callipo, Di Natale e Anastasi \u2013 vuole fare questa ennesima magra figura, mentre i calabresi sono costretti ad affrontare ogni giorno le conseguenze di una crisi economica e sociale gravissima, se ne assuma tutte le responsabilit\u00e0. Non lo far\u00e0 con il nostro voto\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un fatto inedito nella storia del Consiglio regionale calabrese. Ci sono volute 8 ore per mettersi d&#8217;accordo sulle Commissioni consiliari permanenti e sulle due Commissioni speciali<\/p>\n","protected":false},"author":42,"featured_media":131592,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-131591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=131591"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/131592"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=131591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=131591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=131591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}