{"id":131597,"date":"2020-06-13T08:20:46","date_gmt":"2020-06-13T06:20:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-sequestrati-i-beni-del-boss-bartolo-bruzzaniti-per-oltre-un-milione\/"},"modified":"2023-01-16T18:00:50","modified_gmt":"2023-01-16T17:00:50","slug":"358430-ndrangheta-sequestrati-i-beni-del-boss-bartolo-bruzzaniti-per-oltre-un-milione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/358430-ndrangheta-sequestrati-i-beni-del-boss-bartolo-bruzzaniti-per-oltre-un-milione\/","title":{"rendered":"&#8216;Ndrangheta: sequestrati i beni del boss Bartolo Bruzzaniti per oltre un milione"},"content":{"rendered":"<h4>La Divisione anticrimine della Questura di Milano ha eseguito sequestri patrimoniali a carico di Bartolo Bruzzaniti, noto esponente della cosca Morabito-Palamara-Bruzzaniti<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MILANO &#8211; Una carriera criminale iniziata fin da giovanissimo. Bartolo Bruzzaniti, 44 enne di Locri \u00e8 stato denunciato per la prima volta nel 1991 quando appena 15enne, fu coinvolto in una sparatoria. Poi l&#8217;affermazione come referente del clan Morabito-Palamara-Bruzzaniti sul territorio milanese per l&#8217;importazione e lo smistamento di grandi <strong>quantit\u00e0 di cocaina dalla Calabria<\/strong>.<\/p>\n<p>Gi\u00e0 nell&#8217;ottobre 2019, le indagini patrimoniali svolte dai poliziotti della Divisione Anticrimine avevano accertato l&#8217;evidente sperequazione tra i redditi dell&#8217;uomo ed il suo tenore di vita e avevano portato all&#8217;emissione dal Tribunale di Reggio Calabria di un decreto di sequestro di beni per un valore di circa 3 milioni di euro (sei immobili, tre societ\u00e0, un autoveicolo e diversi conti correnti). Il prosieguo delle indagini ha portato gli investigatori ad individuare altri beni del valore di oltre un milione di euro. Sono state sequestrate due imprese di costruzioni e un bar a Garbagnate Milanese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Divisione anticrimine della Questura di Milano ha eseguito sequestri patrimoniali a carico di Bartolo Bruzzaniti, noto esponente della cosca Morabito-Palamara-Bruzzaniti<\/p>\n","protected":false},"author":42,"featured_media":131598,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-131597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=131597"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/131598"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=131597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=131597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=131597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}