{"id":131937,"date":"2020-06-18T18:00:20","date_gmt":"2020-06-18T16:00:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-bassetti-non-ci-sara-seconda-ondata-come-a-marzo-ma-dovremo-convivere-con-covid\/"},"modified":"2023-01-16T18:01:13","modified_gmt":"2023-01-16T17:01:13","slug":"359261-coronavirus-bassetti-non-ci-sara-seconda-ondata-come-a-marzo-ma-dovremo-convivere-con-covid","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/359261-coronavirus-bassetti-non-ci-sara-seconda-ondata-come-a-marzo-ma-dovremo-convivere-con-covid\/","title":{"rendered":"Coronavirus, Bassetti: &#8220;non ci sar\u00e0 seconda ondata come a marzo, ma dovremo convivere con Covid&#8221;"},"content":{"rendered":"<h4><strong>&#8220;Il temuto ed erroneamente profetizzato rimbalzo non c&#8217;\u00e8 stato. Buone notizie sul fronte delle cure&#8221;<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>GENOVA &#8211; \u201cCredo che non ci sar\u00e0 una seconda ondata simile a quella di marzo, ma<strong> dovremo imparare a convivere con il Covid ed essere pronti ad affrontare nuovi casi nel prossimo autunno.<\/strong> Sapere di avere farmaci e presidi che funzionano, ci fa essere ancora pi\u00f9 ottimisti\u201d. Si legge in un post sulla sua pagina Facebook, del <strong>direttore della clinica di Malattie infettive del policlinico San Martino di Genova, il Prof. Matteo Bassetti.<\/strong> &#8220;Sta continuando &#8211; si legge ancora nel post &#8211; la rapida discesa dei casi ospedalizzati di COVID-19 sia in rianimazione che negli altri reparti, con numeri cos\u00ec bassi, che non si vedevano dai primi di marzo. <strong>Non dimentichiamoci che ci\u00f2 che ha fatto giustamente paura al sistema sanitario italiano, in quei giorni di fine inverno, erano i ricoveri ospedalieri,<\/strong> fatti di casi di soggetti altamente sintomatici e gravi, che hanno continuato a crescere fino ai primi di aprile.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-359268 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/06\/matteo-bassetti.jpg\" alt=\"\" width=\"696\" height=\"500\" title=\"\"><\/p>\n<p>I nuovi contagi degli ultimi giorni, fatti per lo pi\u00f9 da asintomatici, preoccupano meno, molto meno, anche se devono avere ovviamente una giusta attenzione da parte del sistema di prevenzione. I catastrofisti e i pessimisti, di cui l&#8217;Italia \u00e8 stata ed \u00e8 ancora piena, non saranno contenti di questi numeri. Io e molti miei colleghi, invece si. <strong>Non dimentichiamoci oltretutto, che questi numeri cos\u00ec incoraggianti, sia di malati veri che di asintomatici, sono quelli post riaperture<\/strong> (4 maggio-18 maggio- 3 giugno). <strong>Il temuto ed erroneamente profetizzato rimbalzo non c&#8217;\u00e8 stato. Anche di questo ci rallegriamo.<\/strong> Per il futuro occorrer\u00e0 valutare pi\u00f9 attentamente e pi\u00f9 criticamente la capacit\u00e0 di previsione dei vari modelli matematici e, forse, ascoltare di pi\u00f9 i medici sul campo.<\/p>\n<p>Direi buone notizie sul fronte delle<strong> cure per il COVID-19. Il cortisone ha dimostrato di ridurre la mortalit\u00e0 del 30% nei pazienti ospedalizzati.<\/strong> Lo dimostrano i risultati dello studio inglese &#8220;Recovery&#8221; annunciati ieri alla stampa. Si tratta dello stesso studio che ha bocciato la clorochina, che \u00e8 stata ritirata dal commercio anche da parte dell&#8217;FDA. Buone notizie ulteriori anche su <strong>remdesivir<\/strong> che in un articolo pubblicato su Nature conferma che la sua somministrazione precoce possa <strong>ridurre il rischio di sviluppare una grave polmonite.<\/strong> Noi a Genova li abbiamo iniziati ad utilizzare entrambi dal principio inserendoli nel nostro protocollo di cura. Ci eravamo accorti dell&#8217;importanza del cortisone e del remdesevir nelle fasi precoci della malattia. Ci avevamo visto lungo&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il temuto ed erroneamente profetizzato rimbalzo non c&#8217;\u00e8 stato. Buone notizie sul fronte delle cure&#8221;<\/p>\n","protected":false},"author":22,"featured_media":131938,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[675],"class_list":["post-131937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-coronavirus-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=131937"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/131937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/131938"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=131937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=131937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=131937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}