{"id":132249,"date":"2020-06-24T11:17:03","date_gmt":"2020-06-24T09:17:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/marano-marchesato-sequestrato-un-campo-da-tiro-sportivo-3-denunce\/"},"modified":"2023-01-16T18:01:34","modified_gmt":"2023-01-16T17:01:34","slug":"360105-marano-marchesato-sequestrato-un-campo-da-tiro-sportivo-3-denunce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/360105-marano-marchesato-sequestrato-un-campo-da-tiro-sportivo-3-denunce\/","title":{"rendered":"Marano Marchesato: sequestrato un campo da tiro sportivo, 3 denunce"},"content":{"rendered":"<h4>I carabinieri Forestali di Cosenza hanno posto sotto sequestro un campo di tiro sportivo in corso di realizzazione in localit\u00e0 \u201cForesta Santoro\u201d<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MARANO MARCHESATO &#8211; Il sequestro \u00e8 avvenuto durante un controllo svolto in localit\u00e0 \u201cForesta Santoro\u201d a seguito di una segnalazione, e i militari si sono recati sul posto per verificare la normativa urbanistico edilizia e paesaggistico ambientale rispetto ai lavori in corso d\u2019opera nel <strong>Campo da Tiro sportivo<\/strong>\u00a0con armi comuni da sparo.<\/p>\n<p>Dal controllo \u00e8 stato accertato che alcune delle <strong>opere realizzate erano prive di permesso a costruire<\/strong> ed altre erano state realizzate, in <strong>totale difformit\u00e0 delle autorizzazioni rilasciate<\/strong>. In particolare \u00e8 stato realizzato un campo da tiro mediante lo scavo di un terreno in assenza di permesso a costruire ed in assenza di autorizzazione paesaggistico ambientale.<\/p>\n<p>Le altre opere erano invece totalmente difformi alle autorizzazioni. Per la realizzazione di parte delle opere edili, senza alcuna autorizzazione, \u00e8 stata anche sradicata una superficie boscata di circa 500 mq dove era presente un bosco di castagno. Tutta l\u2019area \u00e8 stata posta sotto sequestro.<\/p>\n<p>I militari hanno inoltre denunciato alla Procura della Repubblica di Cosenza il <strong>committente<\/strong> dei lavori, il <strong>direttore<\/strong> dei lavori ed il <strong>legale rappresentante<\/strong> dell\u2019impresa esecutrice per violazioni di natura urbanistico edilizia e paesaggistico ambientale e per reati contro la fede pubblica ed il patrimonio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri Forestali di Cosenza hanno posto sotto sequestro un campo di tiro sportivo in corso di realizzazione in localit\u00e0 \u201cForesta Santoro\u201d<\/p>\n","protected":false},"author":42,"featured_media":132250,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-132249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132249"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132250"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}