{"id":132291,"date":"2020-06-24T16:43:27","date_gmt":"2020-06-24T14:43:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/caporalato-flai-e-cgil-ad-amantea-devastazione-e-violazione-dei-diritti-umani\/"},"modified":"2023-01-16T18:01:37","modified_gmt":"2023-01-16T17:01:37","slug":"360242-caporalato-flai-e-cgil-ad-amantea-devastazione-e-violazione-dei-diritti-umani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/360242-caporalato-flai-e-cgil-ad-amantea-devastazione-e-violazione-dei-diritti-umani\/","title":{"rendered":"Caporalato, Flai e Cgil &#8220;ad Amantea devastazione e violazione dei diritti umani&#8221;"},"content":{"rendered":"<h4>Cgil e Flai &#8220;\u00e8 necessario un intervento normativo per inasprimento pene per coloro che traggono beneficio dallo sfruttamento, che deve valere per tutta la filiera. Continueremo ad insistere per attivare percorsi virtuosi e condivisi finalizzati a contrastare ogni forma di sfruttamento&#8221;<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; &#8220;Mentre incessante continua il lavoro delle Forze dell&#8217;Ordine per contrastare la ripugnante pratica del caporalato, fenomeno piuttosto fertile nelle campagne calabresi &#8211; come dimostra l&#8217;ultima operazione messa assegno ad Amantea, denominata &#8220;<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/10626\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Uomini e Caporali<\/strong><\/a><\/span> &#8220;, che ha portato all&#8217;<strong>arresto domiciliare di alcuni imprenditori ed al sequestro di una azienda agricola,<\/strong> al cui interno lavoratori prevalentemente del Bangladesh erano sottoposti a condizioni disumane di vita e di lavoro, con turni di anche 26 ore pagate ad un 1,50 euro, e constanti umiliazioni e privazioni &#8211; la sensazione frustrante \u00e8 che ancora ci sia molto da fare per debellare definitivamente lo sfruttamento del lavoro nell&#8217;agricoltura&#8221;. E&#8217; quanto si affermano in una nota il segretario generale di Flai Cgil Calabria Bruno Costa, Angelo Sposato segretario generale della Cgil Calabria, Giovambattista Nicoletti segretario generale Flai Cgil Cosenza e Umberto Calabrone segretario generale Cgil Cosenza.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10653\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-360246\" src=\"https:\/\/quicosenza.it\/news\/10653\" alt=\"\" width=\"571\" height=\"343\" title=\"\"><\/a><\/p>\n<p>&#8220;Nella fattispecie, del resto &#8211; \u00e8 detto nella nota &#8211; <strong>non \u00e8 solo contestato il reato di caporalato ma emerge una devastante violazione dei diritti umani e di libert\u00e0 come la riduzione in schiavit\u00f9<\/strong>. Noi,lungo tutti questi anni non siamo rimasti immobili a guardare. Anzi, proprio nel territorio di Amantea, in queste ultime settimane, la nostra attivit\u00e0 sindacale si \u00e8 intensificata, andando direttamente nei campi, sui luoghi della raccolta, per offrire la nostra assistenza alle lavoratrici ed ai lavoratori. Donando loro, anche dispositivi di sicurezza come le mascherine, a tutela della loro salute. E&#8217; un fatto significativo, tra l&#8217;altro, che proprio <strong>l&#8217;operazione di queste ore sia scaturita dalla diretta denuncia di alcuni braccianti,<\/strong> che hanno deciso di ribellarsi a questo genere di soprusi&#8221;.<\/p>\n<p>&#8220;Pertanto, \u00e8 necessario &#8211; \u00e8 detto ancora nella nota <strong>&#8211; un intervento normativo per l&#8217;inasprimento delle pene,<\/strong> per coloro che traggono beneficio dallo sfruttamento, che deve valere per tutta la filiera. E ci aspettiamo una condanna ed una presa di posizione da parte del Consorzio cipolla Rossa di Tropea, di cui la societ\u00e0 sequestrata fa parte. Per quanto ci riguarda, continueremo ad insistere, anche nei confronti della politica, per attivare percorsi virtuosi e condivisi finalizzati a contrastare ogni forma di sfruttamento della persona e del lavoro nel settore agricolo, partendo, appunto, dal rafforzare,<strong> valorizzare ed incentivare la rete del lavoro agricolo di qualit\u00e0<\/strong>, dalla piena applicazione della Legge 199\/2016, istituendo collocamento pubblico in agricoltura per sconfiggere il caporalato ed agevolare l&#8217;incontro tra domanda e offerta di lavoro, incrementando i controlli sui territori&#8221;.<\/p>\n<p>&#8220;Come sindacato di categoria &#8211; si sottolinea ancora nella nota &#8211;<strong> continueremo a batterci e mobilitarci per dare giusto sostegno e reali opportunit\u00e0 di sviluppo all&#8217;agricoltura della nostra regione<\/strong>, e maggiori sicurezze e tutele alle lavoratrici ed ai lavoratori agricoli, e gi\u00e0 nei prossimi giorni torneremo in piazza organizzando una significativa mobilitazione di fronte alla Prefettura di Catanzaro. Ci auguriamo che questa sia l&#8217;apertura di una fase per debellare definitivamente il fenomeno del caporalato, grazie anche alle denunce che nel corso degli anni abbiamo fatto come organizzazioni sindacali&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cgil e Flai &#8220;\u00e8 necessario un intervento normativo per inasprimento pene per coloro che traggono beneficio dallo sfruttamento, che deve valere per tutta la filiera. Continueremo ad insistere per attivare percorsi virtuosi e condivisi finalizzati a contrastare ogni forma di sfruttamento&#8221;<\/p>\n","protected":false},"author":55,"featured_media":132292,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-132291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132291"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132292"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}