{"id":132305,"date":"2020-06-25T07:05:57","date_gmt":"2020-06-25T05:05:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-sorpresi-a-rubare-in-un-supermercato-con-la-droga-in-tasca\/"},"modified":"2023-01-16T18:01:37","modified_gmt":"2023-01-16T17:01:37","slug":"360291-rende-sorpresi-a-rubare-in-un-supermercato-con-la-droga-in-tasca","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/360291-rende-sorpresi-a-rubare-in-un-supermercato-con-la-droga-in-tasca\/","title":{"rendered":"Rende, sorpresi a rubare in un supermercato con la droga in tasca"},"content":{"rendered":"<h4>Due giovani sono stati arrestate dai carabinieri di Rende dopo essere stati sorpresi a rubare in un supermercato in via Genova. Il giudice ha convalidato l&#8217;arresto e disposto per entrambi la misura dei domiciliari<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Sono accusati di furto, detenzione ai fini di spaccio di sostanze stupefacenti e resistenza a Pubblico Ufficiale i due giovani, arrestati dai carabinieri di Rende. Si tratta di un <strong>21enne della Gambia residente a Dipignano e di un 24enne senegalese residente a Montalto Uffugo.<\/strong> I due sono stati fermati ieri mattina dai militari dell\u2019Aliquota Radiomobile allertati dal personale di un supermercato in via Genova a Rende. I carabinieri li hanno bloccati nonostante i due inveivano contro gli operanti insultandoli e strattonandoli.\u00a0Nel corso della perquisizione personale oltre alla refurtiva, <strong>consistente in t-shirt, bottiglie di superalcolici e articoli di profumeria<\/strong>, restituita ai legittimi proprietari, i militari rinvenivano, occultata all\u2019interno degli slip dei due giovani,\u00a0 22 involucri in cellophane contenenti <strong>marijuana<\/strong>, per un peso complessivo di <strong>100 grammi, sottoposta a sequestro.\u00a0\u00a0<\/strong><\/p>\n<h4>Concessi i domiciliari<\/h4>\n<p>Questa mattina si \u00e8 tenuta l&#8217;udienza di convalida dell&#8217;arresto dei due giovani, d<strong>ifesi entrambi dall&#8217;avvocato Amalia Falcone<\/strong>, dinanzi al giudice dott.ssa G Urania Granata. Arresto convalidato per entrambi con applicazione della misura<strong> cautelare degli arresti domiciliari<\/strong> (uno gi\u00e0 con autorizzazione al lavoro). Rinvio all&#8217;8 settembre. S<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due giovani sono stati arrestate dai carabinieri di Rende dopo essere stati sorpresi a rubare in un supermercato in via Genova. Il giudice ha convalidato l&#8217;arresto e disposto per entrambi la misura dei domiciliari<\/p>\n","protected":false},"author":42,"featured_media":132306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-132305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132305"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132306"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}