{"id":132451,"date":"2020-06-27T06:00:11","date_gmt":"2020-06-27T04:00:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/stadio-lorenzon-attivarende-un-passo-avanti-e-due-indietro\/"},"modified":"2023-01-16T18:01:48","modified_gmt":"2023-01-16T17:01:48","slug":"360678-stadio-lorenzon-attivarende-un-passo-avanti-e-due-indietro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/360678-stadio-lorenzon-attivarende-un-passo-avanti-e-due-indietro\/","title":{"rendered":"Stadio Lorenzon, AttivaRende: &#8220;un passo avanti e due indietro&#8221;"},"content":{"rendered":"<h4>&#8220;Il sindaco di Rende, supportato da un suo collaboratore, avrebbe richiesto un finanziamento di 350 mila euro per l\u2019adeguamento alle norme di sicurezza e agli standard della Lega Pro dello stadio \u201cLorenzon\u201d. Intervento che, se approvato, sar\u00e0 inserito nel programma triennale dei lavori pubblici 2020-2022&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; Il Gruppo consiliare AttivaRende interviene sulla notizia apparsa ieri anche e relativa <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/10683\" target=\"_blank\" rel=\"noopener noreferrer\">all&#8217;adeguamento dello stadio Lorenzon<\/a><\/strong><\/span>. In particolare i consiglieri Mimmo Talarico e Andrea Cuzzocrea puntano l&#8217;attenzione sui tempi che priveranno la citt\u00e0 di Rende della &#8216;gioia del pallone&#8217;. &#8220;<strong>Siamo ancora nel campo delle ipotesi.<\/strong> Tuttavia la notizia non pu\u00f2 che piacere, soprattutto agli sportivi e alle opposizioni che da tempo hanno chiesto ripetutamente al sindaco di adeguare lo stadio e consentire al Rende calcio di disputare le partite in casa. Invece per un anno intero e probabilmente per un altro ancora, la citt\u00e0 di Rende sar\u00e0 privata dalla gioia del pallone&#8221;.<\/p>\n<p>&#8220;Tutto ci\u00f2 per una storia che merita di essere approfondita in altre sedi. E\u2019 utile ricordare che l\u2019 8 maggio\u00a0 del 2019 la maggioranza del Sindaco Manna concesse in diritto di superficie lo stadio \u201cLorenzon\u201d per la ristrutturazione dello stesso e per la realizzazione di una serie di strutture destinate ad attivit\u00e0 commerciali. Nel frattempo (a ottobre)<strong> le competenti commissioni esaminarono il progetto di ristrutturazione che prevedeva un investimento di quasi 12 milioni di euro, per 7 mila metri quadrati di attivit\u00e0 commerciali<\/strong>. Le minoranze chiesero di realizzare al pi\u00f9 presto i lavori necessari per rendere idoneo il \u201cLorenzon\u201d e quindi riportare il calcio a Rende e al contempo di revocare la delibera e abbandonare il progetto&#8221;.<\/p>\n<p>&#8220;Ma la maggioranza &#8211; proseguono i consiglieri comunali &#8211; and\u00f2 avanti caparbiamente Ma era solo una finta. Durante un consiglio comunale un assessore dichiar\u00f2 finanche che se il Comune non avesse ceduto il diritto di superficie, il Rende calcio non avrebbe potuto iscriversi al campionato. Presumiamo che siano cambiate le regole. Oggi potremmo limitarci a dire che le opposizioni avevano ragione anche quando dicevano di essere in presenza di giunta approsimativa che stava perorando un progetto stranissimo sotto tutti i punti di vista: sportivo, urbanistico, edilizio, sociale, finanziario. A questo punto alcune domande sorgono spontanee: se \u00e8 vero che si proceder\u00e0 alla ristrutturazione, non potevate pensarci prima? Non era abbastanza chiaro che il progetto del Presidente del Rende Calcio e dei suoi sodali era fuori da qualsiasi conteso logico? E chi risarcir\u00e0 le centinaia di tifosi e sportivi di Rende nel frattempo privati dalle emozioni domenicali? Noi ci auguriamo che il progetto venga definitavamente abbandonato, cos\u00ec come <strong>venga abbandonata l\u2019irritante politica degli annunci di questa amministrazione&#8221;.<\/strong><\/p>\n<p><strong>&#8220;<\/strong>Riteniamo che Rende meriti un nuovo stadio, adeguato alle esigenze della categoria e che l\u2019attuale area del \u201cLorenzon\u201d venga riqualificata e in gran parte destinata ad uso pubblico. Per\u00f2, per favore risparmiateci, l\u2019ennesima notizia di uno stadio tutto nuovo. Saremmo al terzo. Il primo avrebbe dovuto finanziarlo il Presidente Oliverio; il secondo sarebbe stato realizzato d\u2019intesa con l\u2019Unical (ricordate il centro sportivo?). Ma visto che si parla di citt\u00e0 unica, cominciamo a realizzarla facendo giocare le due squadre nello stesso stadio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il sindaco di Rende, supportato da un suo collaboratore, avrebbe richiesto un finanziamento di 350 mila euro per l\u2019adeguamento alle norme di sicurezza e agli standard della Lega Pro dello stadio \u201cLorenzon\u201d. Intervento che, se approvato, sar\u00e0 inserito nel programma triennale dei lavori pubblici 2020-2022&#8221;<\/p>\n","protected":false},"author":42,"featured_media":132452,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-132451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132451"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132452"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}