{"id":132515,"date":"2020-06-29T08:00:41","date_gmt":"2020-06-29T06:00:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-consegna-del-primo-bene-comune-alla-consulta-che-lo-autogestira\/"},"modified":"2023-01-16T18:01:52","modified_gmt":"2023-01-16T17:01:52","slug":"360869-rende-consegna-del-primo-bene-comune-alla-consulta-che-lo-autogestira","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/360869-rende-consegna-del-primo-bene-comune-alla-consulta-che-lo-autogestira\/","title":{"rendered":"Rende, il campetto del Villaggio Europa ai cittadini. Consegnato il primo bene comune"},"content":{"rendered":"<h4>Nella piazza di Villaggio Europa\u00e8 stato consegnato ufficialmente alla citt\u00e0 di Rende il primo bene comune che l\u2019amministrazione Manna ha affidato alla consulta che lo autogestir\u00e0 &#8220;g<strong>estione diretta dei cittadini, coinvolgimento e cittadinanza attiva. Siamo orgogliosi&#8221;<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; <strong>Saranno gli stessi cittadini a prendersi cura e amministrare dal basso un bene collettivo<\/strong>. Un esempio concreto di democrazia diretta che vede la cosa pubblica quale bene comune primario. Il progetto pilota \u00e8 partito con il riconoscimento del <strong>campo di calcio di Villaggio Europa<\/strong> come primo bene comune, che \u00e8 stato illustrato alla citt\u00e0 con la presentazione delle tante attivit\u00e0 che si potranno svolgere nello spazio e nell\u2019aree limitrofe. Dal softball al calcio, dalla pallavolo ai giochi da tavolo e ai giochi popolari: si partir\u00e0 dal gioco per progettare un percorso comune all&#8217;insegna della condivisione e dell\u2019<strong>abbattimento di ogni barriera sociale, sessista, razziale<\/strong>.\u00a0<strong>La consulta dei beni comuni<\/strong> avr\u00e0 in gestione il campo sportivo di Villaggio Europa in via sperimentale per dodici mesi dalla sottoscrizione della relativa convenzione.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10693\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-361265\" src=\"https:\/\/quicosenza.it\/news\/10693\" alt=\"\" width=\"570\" height=\"380\" title=\"\"><\/a><\/p>\n<h4>Manna &#8220;amministrare la cosa pubblica insieme con i cittadini<strong>&#8220;<\/strong><\/h4>\n<p>&#8220;Siamo orgogliosi di questo primo traguardo &#8211; ha evidenziato il sindaco Marcello Manna &#8211; che significa <strong>gestione diretta dei cittadini, coinvolgimento e cittadinanza attiva<\/strong>. Oggi si arriva alla consegna del bene Comune. Oggi il primo bene che viene consegnato alla citt\u00e0 di Rende ed in particolare al Villaggio Europa. Dovevamo ristrutturare questo campo, fare una manifestazione di interesse, andare a controllare anche i rapporti economici ecc&#8230; In questo modo bypassiamo tutto perch\u00e8<strong> il bene viene usato da tutti i cittadini e li responsabilizza<\/strong>. Ora questo campo \u00e8 cosa vostra, \u00e8 un bene che appartiene a tutti noi. Ed \u00e8 significativo perch\u00e8 da qui si parte per un passaggio di consapevolezza importante per amministrare la cosa pubblica insieme con i cittadini. \u00c8 un piccolo passo diventa importante per una citt\u00e0 del Sud come Rende.<strong> Riprendiamo il cammino insieme a tutti i cittadini<\/strong> anche dopo l&#8217;emergenza coronavirus, con <strong>una democrazia partecipata che ha un grande significato<\/strong> e un grande valore. E questo \u00e8 solo il primo passo. C&#8217;\u00e8 un gruppo di associazioni particolarmente attenta a queste cose e con loro stiamo discutendo perch\u00e8 ci sono tanti spazi a Rende che possono essere curati dai cittadini-2<\/p>\n<p>\u201c\u00c8 necessario ridare centralit\u00e0 alla convivenza e alla socialit\u00e0, agli affetti, iniziando a imporsi come parte attiva nei progetti di cura e rigenerazione dei beni comuni della propria citt\u00e0 e programmando percorsi che ruotano intorno all\u2019idea di comunit\u00e0, di decisione assembleare, di autogoverno. I beni comuni &#8211; spiega ancora il sindaco &#8211; sono gli <strong>spazi in disuso, le piazze, i beni culturali e quei simboli cittadini troppo spesso trascurati per diverse priorit\u00e0 delle agende politiche.<\/strong> I beni comuni sono <strong>l\u2019acqua, i servizi pubblici di base, l\u2019ambiente, la salute, i servizi<\/strong>. Beni comuni sono le citt\u00e0 e tutti quei quartieri che attraverso la cooperazione quotidiana e costante fra chi li vive non saranno mai ghettizzati. Beni comuni sono tutti quei contesti materiali e immateriali in cui, o attraverso cui, si sprigionano la forza e la passione della cittadinanza attiva. Beni comuni sono beni di tutti, beni comuni sono l\u2019opposto della propriet\u00e0\u201d.\u00a0<a href=\"https:\/\/quicosenza.it\/news\/10694\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-360875\" src=\"https:\/\/quicosenza.it\/news\/10694\" alt=\"\" width=\"623\" height=\"813\" title=\"\"><\/a><\/p>\n<h4>Stefano Ammirato &#8220;un esempio di democrazia diretta&#8221;<\/h4>\n<p>&#8220;A noi piace definirlo <strong>democrazia diretta o autogoverno<\/strong>. Un pezzo di citt\u00e0 collettivo, in questo caso un campo sportivo con spogliatoi, dove fare <strong>una polisportiva e una policreativa per attivit\u00e0 sociali, ludiche e sportive per animare il quartiere<\/strong> e, sopratutto, per far un esperimento di gestione collettiva ma non di un privato&#8221; ha detto Stefano Ammirato, componente del comitato del quartiere Villaggio Europa e del coordinamento Decidiamo noi che ha proposto il regolamento dei beni comuni alla citt\u00e0 di Rende dove, sottolinea, &#8220;associazioni, cittadini e quartiere sono tutti insieme per realizzare cose belle. Questo \u00e8 un progetto che significa anche integrazione perch\u00e8 ci sono tante persone non solo del quartiere che vengono qui con tanti progetti. <strong>Una decina di associazioni le associazioni che hanno aderito al progetto<\/strong> come AIPD, Acrip, Associazione Villaggio Europa casa dei diritti sociali, Auser Rende, Sparrow, Sud Comune, Cosenza Mmiskhata, Associazione insieme e tante altre. E tutto questo non solo per bimbi e persone con disabilit\u00e0 ma anche per anziani e per tutti quelli che vogliono divertirsi&#8221;.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Foto Francesco Greco<\/strong><\/span><\/p>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella piazza di Villaggio Europa\u00e8 stato consegnato ufficialmente alla citt\u00e0 di Rende il primo bene comune che l\u2019amministrazione Manna ha affidato alla consulta che lo autogestir\u00e0 &#8220;gestione diretta dei cittadini, coinvolgimento e cittadinanza attiva. Siamo orgogliosi&#8221;<\/p>\n","protected":false},"author":42,"featured_media":132516,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-132515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132515"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132516"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}