{"id":132591,"date":"2020-06-30T07:25:34","date_gmt":"2020-06-30T05:25:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-boss-della-ndrangheta-padrone-dellhotel-in-liguria\/"},"modified":"2023-01-16T18:01:57","modified_gmt":"2023-01-16T17:01:57","slug":"361092-il-boss-della-ndrangheta-padrone-dellhotel-in-liguria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/361092-il-boss-della-ndrangheta-padrone-dellhotel-in-liguria\/","title":{"rendered":"Il boss della &#8216;ndrangheta &#8220;padrone&#8221; dell&#8217;hotel in Liguria"},"content":{"rendered":"<h4>Stamattina l&#8217;arresto del figlio del boss Domenico Pio, insieme ad altre tre persone. Alfonso Pio avrebbe anche imposto che la sua compagna &#8220;soggiornasse gratuitamente in una suite a lei riservata&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MILANO &#8211; <strong>Alfonso Pio, 52 anni<\/strong> e figlio di Domenico Pio boss del clan della &#8216;ndrangheta di Desio (Monza), arrestato nella maxi inchiesta &#8216;Infinito&#8217; del 2010, sarebbe diventato il &#8220;padrone&#8221; dell&#8217;Hotel del Golfo di Finale Ligure (Savona). L&#8217;indagine \u00e8 stata condotta dalla polizia postale e ad Alfonso Pio viene contestata, tra le altre cose, <strong>un&#8217;estorsione aggravata dal metodo mafioso<\/strong> perch\u00e9, assieme ad un altro degli arrestati, <strong>Omar Petrocca, &#8220;con minacce&#8221; avrebbe costretto i soci della Confort Hotels &amp; Resorts srl,<\/strong> &#8220;societ\u00e0 proprietaria dell&#8217;Hotel del Golfo&#8221;, a consegnare allo stesso Petrocca &#8220;i certificati cartacei attestanti la titolarit\u00e0 delle quote della societ\u00e0&#8221;.<\/p>\n<p>Questo per &#8220;ottenere il controllo di quest&#8217;ultima, senza dar seguito al contratto preliminare di vendita delle medesime quote gi\u00e0 stipulato&#8221; con un altro socio. Cos\u00ec Pio avrebbe ottenuto nel 2018 il &#8220;controllo della societ\u00e0&#8221; e del resort. Alfonso Pio, pure cugino di Candeloro Pio, anche lui arrestato nella maxi indagine &#8216;Infinito&#8217; di dieci anni fa e capo della &#8216;locale&#8217; di Desio, avrebbe fatto valere la sua &#8220;appartenenza&#8221; alla &#8216;ndrangheta per imporsi sulle &#8220;vittime&#8221;.<\/p>\n<p>Fin dal 2016, poi, avrebbe imposto che la sua compagna Nelli Gubina, detta Stella, &#8220;soggiornasse gratuitamente in una suite a lei riservata, sia nella stagione estiva che in quella invernale nonostante l&#8217;hotel fosse chiuso al pubblico da ottobre ad aprile&#8221;. Nel giugno 2018 avrebbe anche minacciato &#8220;di morte&#8221; un dipendente dell&#8217;hotel dicendogli &#8220;che Stella &#8216;pu\u00f2 prendere quello che vuole &#8230; sono io il capo&#8217;&#8221; e il primo agosto 2018 lo avrebbe picchiato &#8220;impossessandosi dei contanti presenti in cassa&#8221;. L&#8217;appartenenza alla &#8216;ndrangheta di Pio, si legge nell&#8217;ordinanza, veniva prospettata &#8220;anche da Petrocca in alcuni colloqui&#8221; con uno dei soci della societ\u00e0 dell&#8217;hotel. Petrocca diceva che Pio era una persona &#8220;difficile da far ragionare&#8221;.<\/p>\n<h4>Le minacce al socio, ecco come la &#8216;ndrangheta avrebbe ottenuto il controllo dell&#8217;albergo<\/h4>\n<p><em>&#8220;Non posso venire &#8230; tengo famiglia &#8230; non posso venire&#8221;.<\/em> Cos\u00ec uno dei soci della societ\u00e0 proprietaria dell&#8217;Hotel del Golfo di Finale Ligure, finito in mano alla &#8216;ndrangheta, parlava dell&#8217;impossibilit\u00e0 di presentarsi nell&#8217;aprile 2018 all&#8217;assemblea dei soci dopo le minacce che avrebbe subito da Alfonso Pio. Anche in occasione di una successiva assemblea dei soci, il 12 giugno del 2018 a Milano &#8211; si legge nell&#8217;ordinanza del gip\u00a0 &#8211; <strong>Alfonso Pio &#8220;minacciava&#8221; lo stesso socio<\/strong> che, poi, gli diceva &#8220;questa \u00e8 la seconda volta che io faccio saltare la riunione &#8230; e mi piglio io le responsabilit\u00e0 &#8230; ho fatto quello che volevate&#8221;. Sempre a seguito &#8220;dello stato di intimidazione&#8221; il socio e sua moglie, anche lei nella societ\u00e0, il 28 agosto 2018 facevano consegnare gli &#8220;originali dei certificati azionari&#8221; a Omar Petrocca, uno degli arrestati, &#8220;che li esibiva all&#8217;assemblea del giorno seguente e se ne impossessava&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stamattina l&#8217;arresto del figlio del boss Domenico Pio, insieme ad altre tre persone. Alfonso Pio avrebbe anche imposto che la sua compagna &#8220;soggiornasse gratuitamente in una suite a lei riservata&#8221;<\/p>\n","protected":false},"author":42,"featured_media":132592,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-132591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132591"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132592"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}