{"id":132749,"date":"2020-07-02T09:55:46","date_gmt":"2020-07-02T07:55:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/evade-dai-domiciliari-due-volte-nella-stessa-settimana-arrestato-50enne-di-cassano\/"},"modified":"2023-01-16T18:02:07","modified_gmt":"2023-01-16T17:02:07","slug":"361486-evade-dai-domiciliari-due-volte-nella-stessa-settimana-arrestato-50enne-di-cassano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/361486-evade-dai-domiciliari-due-volte-nella-stessa-settimana-arrestato-50enne-di-cassano\/","title":{"rendered":"Evade dai domiciliari due volte nella stessa settimana, arrestato 50enne di Cassano"},"content":{"rendered":"<h4>L&#8217;uomo era ai domiciliari perch\u00e9 accusato di minacce, danneggiamenti, estorsione di denaro e di maltrattamenti in famiglia<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO &#8211; ROSSANO &#8211; I carabinieri hanno tratto in arresto per il reato di evasione un 50nne del posto, <strong>gi\u00e0 evaso meno di una settimana fa.<\/strong> L\u2019uomo si trova da maggio scorso sottoposto alla misura degli arresti domiciliari a seguito dell\u2019ordinanza emessa dal Gip di Castrovillari, che sostituiva quella precedente della detenzione in carcere, in quanto imputato per i reati d\u2019incendio, maltrattamenti in famiglia ed estorsione. Per questi fatti, nel dicembre scorso, era stato destinatario di un\u2019ordinanza applicativa della custodia cautelare in carcere, poich\u00e9 le indagini condotte dai militari della tenenza di Cassano all\u2019Ionio avevano accertato un continuativo comportamento di vessazioni, minacce, danneggiamenti, estorsione di denaro e di maltrattamenti in famiglia, tenuto dal 50enne a danno dei congiunti e che era culminato con l\u2019incendio della abitazione dove gli stessi abitavano.<br \/>\nNella mattina di ieri, durante un servizio perlustrativo del territorio, i militari sono stati avvisati dalla comunit\u00e0 terapeutica dove l\u2019uomo \u00e8 ristretto agli arresti domiciliari che il detenuto si era volontariamente allontanato, senza alcuna autorizzazione e in violazione delle prescrizioni imposte dal giudice. <strong>Qualche ora dopo i carabinieri lo hanno trovato davanti a un locale nel centro di Cassano<\/strong> e lo hanno tratto in arresto per il reato di evasione. D\u2019intesa con la Procura della Repubblica di Castrovillari \u00e8 stato di nuovo sottoposto agli arresti domiciliari nella struttura dove si trova in cura in attesa di essere giudicato con rito direttissimo in cui la magistratura si pronuncer\u00e0 anche su un eventuale aggravio della misura cautelare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo era ai domiciliari perch\u00e9 accusato di minacce, danneggiamenti, estorsione di denaro e di maltrattamenti in famiglia<\/p>\n","protected":false},"author":56,"featured_media":132750,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-132749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132749"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132750"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}