{"id":132846,"date":"2020-07-04T18:00:16","date_gmt":"2020-07-04T16:00:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/legge-omotransfobia-bruno-bossio-norma-da-difendere-per-affermare-diritto-di-amare\/"},"modified":"2023-01-16T18:02:14","modified_gmt":"2023-01-16T17:02:14","slug":"361755-legge-omotransfobia-bruno-bossio-norma-da-difendere-per-affermare-diritto-di-amare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/361755-legge-omotransfobia-bruno-bossio-norma-da-difendere-per-affermare-diritto-di-amare\/","title":{"rendered":"Legge omotransfobia, Bruno Bossio: &#8220;norma da difendere per affermare diritto di amare&#8221;"},"content":{"rendered":"<h4><strong>&#8220;Difendiamo questa legge,<\/strong>\u00a0facciamolo per le <strong>vittime quotidiane della violenza sessista,<\/strong> per i nostri giovani che hanno il diritto di vivere in un mondo in cui ognuno possa essere libero di amare&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; &#8220;Dietro gli attacchi alla proposta di legge sull\u2019omotransfobia si nascondono retaggi irrazionali e profonde incrostazioni liberticida. In un Paese che ha finalmente varato le Unioni civili e che abbraccia con coraggio la stagione dei diritti, <strong>difendere l&#8217;identit\u00e0 di genere e riconoscere il valore della diversit\u00e0 contro discriminazioni, violenze e subdole emarginazioni dovrebbe essere un atto coerente e anzi conseguente<\/strong>. Ecco perch\u00e9 ho sottoscritto anch&#8217;io, insieme a tante e tanti parlamentari, questa proposta normativa&#8221;. Ad affermarlo \u00e8 la parlamentare del Pd, <strong>Enza Bruno Bossio,<\/strong> che aggiunge: &#8220;Ed ecco perch\u00e9 risultano insopportabili gli attacchi al primo firmatario della legge Alessandro Zan portati avanti da un anomalo fronte unico che vede insieme destre e mondo pro life, femministe radicali e ultraconservatori. <strong>Difendiamo questa legge<\/strong> &#8211; conclude la deputata &#8211; facciamolo per le <strong>vittime quotidiane della violenza sessista,<\/strong> per i nostri giovani che hanno il diritto di vivere in un mondo in cui ognuno possa essere libero di amare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Difendiamo questa legge,\u00a0facciamolo per le vittime quotidiane della violenza sessista, per i nostri giovani che hanno il diritto di vivere in un mondo in cui ognuno possa essere libero di amare&#8221;<\/p>\n","protected":false},"author":22,"featured_media":132847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-132846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=132846"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/132846\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/132847"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=132846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=132846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=132846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}