{"id":133178,"date":"2020-07-09T15:10:39","date_gmt":"2020-07-09T13:10:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-rossano-sequestrate-opere-edilizie-abusive-e-denunciati-i-proprietari\/"},"modified":"2023-01-16T18:02:35","modified_gmt":"2023-01-16T17:02:35","slug":"362654-corigliano-rossano-sequestrate-opere-edilizie-abusive-e-denunciati-i-proprietari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/362654-corigliano-rossano-sequestrate-opere-edilizie-abusive-e-denunciati-i-proprietari\/","title":{"rendered":"Corigliano-Rossano, sequestrate opere edilizie abusive e denunciati i proprietari"},"content":{"rendered":"<h4>I controlli dei militari si sono concentrati in localit\u00e0 <strong>Fabrizio Grande del Comune di Corigliano-Rossano area urbana di Corigliano<\/strong> dove si \u00e8 accertato la costruzione di due immobili abusivi<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO-ROSSANO (CS) &#8211; Nell\u2019ambito di servizi di prevenzione e repressione di reati in danno all\u2019ambiente, con specifico riferimento al <strong>contrasto dell\u2019abusivismo edilizio<\/strong>, i militari della Stazione Carabinieri Forestale di Corigliano Calabro, hanno nei giorni scorsi <strong>denunciato tre persone del luogo.<\/strong> I controlli dei militari si sono concentrati in localit\u00e0 <strong>Fabrizio Grande del Comune di Corigliano-Rossano area urbana di Corigliano<\/strong> dove si \u00e8 accertato la costruzione di due immobili abusivi.<\/p>\n<p>Il primo,<strong> una civile abitazione ultimata di recente,<\/strong> composta da due piani fuori terra ognuno dell\u2019ampiezza di circa 120 metri quadri e piano seminterrato. La struttura rifinita esternamente e dotata di arredi \u00e8 risultata essere stata realizzata da alcuni anni senza nessun titolo abilitativo previsto o elaborati tecnici prodotti. Ci\u00f2 ha comportato una modifica sostanziale all\u2019assetto territoriale ed urbanistico della zona tra l\u2019altro sottoposta a vincolo paesaggistico. Per tale reato si \u00e8 proceduto a deferire il proprietario. Sono invece scattati i <strong>sigilli per un altro manufatto in cemento di 120 metri quadri, ancora non ultimato e con lavori in corso di esecuzione<\/strong>, per il quale anche in questo caso non \u00e8 stata prodotta nessuna autorizzazione prevista. Oltre al sequestro del manufatto si \u00e8 proceduto al deferimento all\u2019Autorit\u00e0 Giudiziaria del proprietario, nonch\u00e9 committente dei lavori, e dell\u2019esecutore materiale degli stessi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I controlli dei militari si sono concentrati in localit\u00e0 Fabrizio Grande del Comune di Corigliano-Rossano area urbana di Corigliano dove si \u00e8 accertato la costruzione di due immobili abusivi<\/p>\n","protected":false},"author":22,"featured_media":133179,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-133178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=133178"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133179"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=133178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=133178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=133178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}