{"id":133218,"date":"2020-07-26T12:00:56","date_gmt":"2020-07-26T10:00:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/durante-il-lockdown-aumentati-gli-abbonamenti-per-ascoltare-musica-in-streaming\/"},"modified":"2023-01-16T18:02:39","modified_gmt":"2023-01-16T17:02:39","slug":"362743-durante-il-lockdown-aumentati-gli-abbonamenti-per-ascoltare-musica-in-streaming","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/362743-durante-il-lockdown-aumentati-gli-abbonamenti-per-ascoltare-musica-in-streaming\/","title":{"rendered":"Durante il lockdown aumentati gli abbonamenti per ascoltare musica in streaming"},"content":{"rendered":"<h4>Il coronavirus e il conseguente lockdown hanno spinto il mercato della musica in streaming<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Tra gennaio e marzo gli abbonamenti ai servizi come Spotify e Amazon Music sono infatti aumentati del 35% su base annua, raggiungendo i 394 milioni su scala globale. Lo certificano gli analisti di Counterpoint. A trainare, oltre ai periodi di prova gratuiti e agli sconti nei mercati emergenti, \u00e8 stato l&#8217;ascolto da casa su smart speaker e tv, mentre sono diminuite le ore d&#8217;ascolto su Android Auto di Google e Car Play di Apple. A livello geografico, la crescita pi\u00f9 consistente si \u00e8 registrata in Asia Pacifico e America latina.<\/p>\n<p>Tra le aziende Spotify conferma la leadership. Nel primo trimestre l&#8217;azienda svedese ha conquistato il 33% degli abbonamenti e il 30% dei ricavi complessivi. Segue Apple Music con il 21% degli abbonati e il 25% delle entrate. Raggiunge il terzo posto Amazon Music, che nel trimestre ha raddoppiato (+104%) il numero di abbonati ottenendo una market share del 12%. YouTube Music conta il 9% degli abbonati totali e Pandora il 5%, mentre tutti gli altri servizi, nel complesso, rappresentano il 19%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il coronavirus e il conseguente lockdown hanno spinto il mercato della musica in streaming<\/p>\n","protected":false},"author":56,"featured_media":133219,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[681],"class_list":["post-133218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=133218"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133219"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=133218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=133218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=133218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}