{"id":133287,"date":"2020-07-11T15:00:08","date_gmt":"2020-07-11T13:00:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/estate-2020-saranno-vacanze-brevi-e-di-prossimita\/"},"modified":"2023-01-16T18:02:44","modified_gmt":"2023-01-16T17:02:44","slug":"362946-estate-2020-saranno-vacanze-brevi-e-di-prossimita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/362946-estate-2020-saranno-vacanze-brevi-e-di-prossimita\/","title":{"rendered":"Estate 2020, saranno vacanze brevi e di prossimit\u00e0. Crisi per le citt\u00e0 d&#8217;arte"},"content":{"rendered":"<h4>Un panorama di grande incertezza. Solo il 36% degli intervistati che intende partire dichiara di avere gi\u00e0 prenotato la vacanza da fare entro settembre, una percentuale incredibilmente bassa in questo periodo dell&#8217;anno<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Vacanze brevi e di prossimit\u00e0 quest&#8217;estate secondo un sondaggio dell&#8217;Osservatorio Confturismo Confcommercio e Swg sull&#8217;indice di fiducia del viaggiatore relativo a giugno. Al centro la &#8220;qualit\u00e0&#8221; della vacanza programmata: quasi <strong>4 intervistati su 10<\/strong> pensano di fare una <strong>vacanza breve, di 2 o 3 giorni,<\/strong> non lontano da casa,<strong> e diventano 1 su 2<\/strong> se si contano anche quelli che ipotizzano vacanze di almeno una settimana, ma sempre senza spostarsi molto dalla residenza abituale.<\/p>\n<p>Nel dettaglio della rilevazione, aumentano di 3 punti &#8211; dal 35% al 38% in un mese &#8211; gli intervistati che dichiarano di volersi concedere una vacanza nei prossimi mesi, ma restano in molti &#8211; il 39% &#8211; a dire che comunque aspetteranno a spostarsi da casa. A questi ultimi si somma poi un ulteriore 19% di indecisi che vorrebbero partire ma temono di non avere disponibilit\u00e0 economiche o di ferie sufficienti. Un panorama di grande incertezza, quindi, confermato dal fatto che solo il 36% degli intervistati che intende partire dichiara di avere gi\u00e0 prenotato la vacanza da fare entro settembre, una percentuale incredibilmente bassa in questo periodo dell&#8217;anno.<\/p>\n<h3>Mare, enogastronomia, benessere e itinerari green<\/h3>\n<p>Le vacanze italiane 2020 segnano implacabile la crisi delle citt\u00e0 d&#8217;arte. L&#8217;indice di fiducia del viaggiatore relativo a giugno vede il 93% degli intervistati, ben il 16% in pi\u00f9 dello scorso anno, far\u00e0 ferie in Italia. <strong>Mete privilegiate Puglia, Toscana e Sicilia<\/strong>. Citt\u00e0 e luoghi d&#8217;arte, di solito in vetta alle preferenze, si piazzano al quarto posto fra le preferenze degli intervistati, menzionate dal 15% contro il 22% dello scorso anno. Per il 7% che invece opter\u00e0 per mete estere, la scelta non pu\u00f2 che restringersi al panorama europeo dove a Grecia, Francia e Spagna, gi\u00e0 in auge lo scorso anno, si aggiunge come new entry l&#8217;Austria che sostituisce l&#8217;Inghilterra, normalmente presente fra le destinazioni top dell&#8217;era pre-Covid.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un panorama di grande incertezza. Solo il 36% degli intervistati che intende partire dichiara di avere gi\u00e0 prenotato la vacanza da fare entro settembre, una percentuale incredibilmente bassa in questo periodo dell&#8217;anno<\/p>\n","protected":false},"author":42,"featured_media":133288,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-133287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=133287"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133288"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=133287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=133287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=133287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}