{"id":133403,"date":"2020-07-13T19:06:25","date_gmt":"2020-07-13T17:06:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-cosenza-lotta-vince-e-tiene-ancora-accesa-la-fiammella-perugia-battuto-2-a-1\/"},"modified":"2023-01-16T18:02:52","modified_gmt":"2023-01-16T17:02:52","slug":"363310-il-cosenza-lotta-vince-e-tiene-ancora-accesa-la-fiammella-perugia-battuto-2-a-1","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/363310-il-cosenza-lotta-vince-e-tiene-ancora-accesa-la-fiammella-perugia-battuto-2-a-1\/","title":{"rendered":"Il Cosenza lotta, vince e tiene ancora accesa la fiammella. Perugia battuto 2 a 1"},"content":{"rendered":"<h4>I rossoblu tornano al successo battendo 2 a 1 il Perugia dal termine di una gara al cardiopalma e piena di occasioni, soprattutto nel finale. Sblocca Bruccini a inizio primo tempo, Baez raddoppia nella ripresa con un eurogoal, ma Falcinelli riapre il match che Capela blinda con un miracolo sulla linea di porta. <!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Un Cosenza letteralmente trasformato, rispetto all&#8217;impalpabile gara di La Spezia, batte 2 a 1 il Perugia al Marulla al termine di una gara dominata nel primo tempo, sofferta e sudata come non mai nella ripresa, ma portata a casa con le unghie e con i denti. Vittoria che permette ai rossoblu, quantomeno, di continuare a rimanere aggrappati alla lotta salvezza. Rossoblu subito pimpanti che trovano il <strong>vantaggio al 12&#8242; con il piattone di Bruccini<\/strong> che corregge in rete la spizzata di Capela sul corner di Baez. Riviere e Asencio, per la prima volta insieme da primo minuto, sono una costante spina nel fianco della difesa umbra. Nella ripresa il Perugia si sveglia, alza il baricentro e mette in apprensione la retroguardia del Cosenza che proprio nel momento di maggiore sofferenza, trova il <strong>raddoppio al 75&#8242; grazie al sigillo di Baez<\/strong>, di gran lunga il migliore in campo. Corsa di 40 metri e tocco morbido a superare Vicario in uscita. Gara chiusa? Neanche per sogno, perch\u00e9<strong> 3 minuti dopo Falcinelli accorcia le distanze<\/strong> insaccando di testa un corner dalla destra. Negli minuti di recupero succede di tutto a cominciare dal <strong>prodigioso intervento di Capela<\/strong> che sulla linea di porta respinge con un miracolo la girata a botta sicura di Capone. Dall&#8217;altra parte <strong>Asencio prima e Sciaudone dopo si divorano in modo clamoroso il tris<\/strong>. Poi il triplice fischio \u00e8 una liberazione per i rossoblu che restano ancora in vita e possono continuare a sperare.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10804\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-363361\" src=\"https:\/\/quicosenza.it\/news\/10804\" alt=\"\" width=\"550\" height=\"390\" title=\"\"><\/a><\/p>\n<h4>Buon Cosenza, la sblocca Bruccini<\/h4>\n<p>Turn-over per Occhiuzzi che deve anche rinunciare al portiere Perina infortunato dell&#8217;ultim&#8217;ora. Per la prima volta in campo dal primo minuto Riviere e Asencio con Baez a completare il tridente. Sull&#8217;out di destra c&#8217;\u00e8 Corsi al posto di Casasola mentre Capela in difesa \u00e8 preferito a Schiavi. A centrocampo torna titolare Sciaudone. Nonostante il gran caldo i rossoblu partono determinati prendendo subito in mano le redini della gara. Dopo 10 minuti di pressione costante e aver sfiorato all&#8217;11 il vantaggio con un <strong>incursione di Baez<\/strong> e un tiro a botta sicura deviato da un difensore, <strong>sul susseguente angolo Capela spizza di testa e capitan Bruccini, appostato sul secondo palo, sblocca la gara<\/strong> insaccando con il piattone lo spiovente dello stesso Baez e trovando suo nono goal stagionale. con il Perugia costretto a rincorrere i rossoblu provano ad approfittare degli spazi e attorno al 20&#8242; si rendono nuovamente pericolosi con una ripartenza due contro due che per\u00f2 n\u00e9 Rivi\u00e8re prima, n\u00e9 Corsi dopo, riescono a concretizzare. Iemmello protesta per una trattenuta in area, dall&#8217;altra parte fa la stessa cosa Riviere. In entrambe le circostanze Ghersini di Genova fa proseguire. <strong>Al 36&#8242; la prima vera occasione del Perugia con il solito Iemmello.<\/strong> L&#8217;attaccante anticipa centralmente l&#8217;uscita di Saracco, ma si allunga la sfera che si perde sul fondo. Funziona la coppia Riviere Asencio. I due si cercano spesso di trovano e al 43&#8242; costruiscono un&#8217;altra occasione. <strong>Riviere libera con un tocco morbido\u00a0 Asencio che a giro di destro<\/strong> sul secondo palo manda fuori di poco. \u00c8 l&#8217;ultima occasione del primo tempo che si chiude dopo 4&#8242; di recupero con il vantaggio dei lupi.<\/p>\n<h4>Eurogoal di Baez, Falcinelli accorcia<\/h4>\n<p>La ripresa si apre con un doppio cambio ordinato da Cosmi che prova a dare pi\u00f9 verve alle azioni offensive del Perugia che a<strong>l 50&#8242; ha un&#8217;ottima occasione con Iemmello<\/strong> liberato in area, ma Idda \u00e8 miracoloso nel recupero e con una scivolata riesce ad evitare la conclusione dell&#8217;attaccante. Lo stesso fa sul nuovo entrato Bonaiuto due minuti dopo. Il Perugia spinge e il Cosenza prova a colpire in ripartenza. Al 50&#8242; Baez rifinisce per Asencio ma la conclusione \u00e8 debole e centrale. Sul capovolgimento di fronte <strong>destro micidiale di Boniuato<\/strong> e palla che esce di un nulla alla destra di Saracco. Non \u00e8 pi\u00f9 il Cosenza del primo tempo, la squadra sembra in debito d&#8217;ossigeno, si allunga pericolosamente e a centrocampo gli umbri trovano sempre spazi per le loro incursioni. Allora Occhiuzzi cambia, inserendo Kone per Riviere e rimodulando la sqaudra con un 5 3 2. Ma proprio nel momento peggiore <strong>il Cosenza al 74&#8242; trova il raddoppio un eurogoal di Baez<\/strong> che palla la piede si fa tutto quasi tutto il campo superando in velocit\u00e0 due avversari e superando Vicario con un tocco morbido. Ma il Perugia non molla e 3 minuti dopo <strong>accorcia le distanze con un<\/strong> <strong>colpo di testa di Falcinelli<\/strong> che raccoglie un corner battuto dalla destra e fa secco Saracco. Entra Casasola al posto di Corsi e al minuto 84&#8242; va vicino al goal con un<strong> destro a giro da posizione impossibile<\/strong> che esce di poco. Gli ultimi minuti sono di sofferenza con il Perugia tutto riversato nella met\u00e0 campo del Cosenza.\u00a0 Nei minuti di recupero succede di tutto. <strong>Capela compie un vero miracolo sulla linea<\/strong> risputando in campo la girata di Capone. <strong>Asencio di divora il 3 a 1<\/strong> in ripartenza cos\u00ec come Sciaudone. Poi pi\u00f9 nulla, con il Cosenza che porta a casa i 3 punti e rimane ancora aggrappato alla lotta salvezza.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><strong>COSENZA CALCIO (3-4-3)<\/strong>: Saracco, Corsi (81&#8242; Casasola), Capela, Idda, Asencio, Sciaudone, Legittimo, Bruccini, Bittante, Riviere (65&#8242; Kone), Baez (86&#8242; Carretta)<br \/>\n<strong>Panchina: <\/strong>Quintiero, Lazaar, Broh, Carretta, D&#8217;Orazio, Bahlouli, Schiavi, Casasola, Machach, Monaco, Kone, Prezioso<br \/>\n<strong>Allenatore:<\/strong> Roberto Occhiuzzi<\/p>\n<p><strong>AC PERUGIA (3-5-2)<\/strong>: Vicario, Rosi, Carraro, Mazzocchi, Iemmello (80&#8242; Capone), Nicolussi, Di Chiara, Kouan (66&#8242; Falcinelli), Gyomber (76&#8242; Angella), Rajkovic (46&#8242; Falasco), Melchiorri (46&#8242; Bonaiuto)<br \/>\n<strong>Panchina: <\/strong>Fulignati, Albertoni, Nzita, Falcinelli, Dragomir, Buonaiuto, Konate, Benzar, Falasco, Capone, Righetti, Angella<br \/>\n<strong>Allentore: <\/strong>Serse Cosmi<\/p>\n<p><strong>Arbitro:<\/strong> Signor Davide Ghersini\u00a0di Genova<br \/>\n<strong>Assistenti: <\/strong>Signori Luigi\u00a0Lanotte\u00a0di Barletta e Alessandro\u00a0Cipressa\u00a0di Lecce<br \/>\n<strong>IV Uomo: <\/strong>Signor Ivano Pezzuto di Lecce<\/p>\n<p><strong>Ammoniti: <\/strong>Sciaudone (C), Rosi (P), Corsi (C)<br \/>\n<strong>Espulsi:<\/strong><\/p>\n<p><strong>Angoli: <\/strong>4-5<br \/>\n<strong>Recupero: <\/strong>4&#8242; p.t. &#8211; 6&#8242; s.t.<\/p>\n<p><strong>Note:<\/strong> Pomeriggio estivo e caldo a Cosenza con una temperatura intorno ai 30 gradi. Terreno del Marulla in perfette condizioni. Gara a porte chiuse senza tifosi per le disposizioni del Governo sulla sicurezza<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I rossoblu tornano al successo battendo 2 a 1 il Perugia dal termine di una gara al cardiopalma e piena di occasioni, soprattutto nel finale. Sblocca Bruccini a inizio primo tempo, Baez raddoppia nella ripresa con un eurogoal, ma Falcinelli riapre il match che Capela blinda con un miracolo sulla linea di porta.<\/p>\n","protected":false},"author":23,"featured_media":133404,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-133403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=133403"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133404"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=133403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=133403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=133403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}