{"id":133603,"date":"2020-07-16T15:50:03","date_gmt":"2020-07-16T13:50:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/escherichia-coli-due-punti-non-conformi-a-paola-e-fuscaldo\/"},"modified":"2023-01-16T18:03:05","modified_gmt":"2023-01-16T17:03:05","slug":"363869-escherichia-coli-due-punti-non-conformi-a-paola-e-fuscaldo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/363869-escherichia-coli-due-punti-non-conformi-a-paola-e-fuscaldo\/","title":{"rendered":"Escherichia coli: due punti non conformi a Paola e Fuscaldo"},"content":{"rendered":"<h4>Il Servizio tematico acque del Dipartimento provinciale Arpacal di Cosenza ha trasmesso oggi ai Comuni di Paola e Fuscaldo, l\u2019esito dei prelievi di campioni di acqua di balneazione prelevati in data 15 luglio<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PAOLA (CS) &#8211; Per Paola, non conformi i valori relativi alle stazioni di campionamento denominate <strong>\u201c100 mt sx torrente San Francesco\u201d<\/strong> &#8211; con sforamento della <strong>Escherichia coli<\/strong> pari a 2000 UFC\/100 ml. (valore limite 500) &#8211; e <strong>\u201c100 mt dx torrente San Francesco\u201d<\/strong> &#8211; con sforamento della Escherichia coli pari a 1400 UFC\/100 ml. Stessa comunicazione \u00e8 stata inviata al Comune di Fuscaldo: non conformi i valori relativi alla stazione di campionamento denominata <strong>\u201c100 mt dx torrente Maddalena\u201d<\/strong>, con sforamento di Escherichia coli pari a 660 UFC\/100 ml. (valore limite 500).<\/p>\n<p>Spetta ai comuni, come richiesto dall\u2019Arpacal, comunicare all\u2019Agenzia le misure di gestione intraprese, come <strong>l\u2019individuazione delle cause di inquinamento, i programmi d&#8217;intervento, la rimozione delle cause,<\/strong> nonch\u00e9 le relative ordinanze sindacali di divieto alla balneazione per i tratti indicati. Si precisa che la denominazione dei punti della <strong>campagna di balneazione<\/strong>, a volte individuati con nome di localit\u00e0 o stabilimenti balneari\/alberghieri, non \u00e8 frutto di una scelta discrezionale Arpacal ma la codificazione dei punti per come stabiliti da Regione e Ministero della Salute.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Servizio tematico acque del Dipartimento provinciale Arpacal di Cosenza ha trasmesso oggi ai Comuni di Paola e Fuscaldo, l\u2019esito dei prelievi di campioni di acqua di balneazione prelevati in data 15 luglio<\/p>\n","protected":false},"author":22,"featured_media":133604,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-133603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=133603"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133604"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=133603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=133603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=133603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}