{"id":133817,"date":"2020-08-08T17:30:10","date_gmt":"2020-08-08T15:30:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/monopattini-elettrici-boom-di-vendite-in-italia\/"},"modified":"2023-01-16T18:03:19","modified_gmt":"2023-01-16T17:03:19","slug":"364507-monopattini-elettrici-boom-di-vendite-in-italia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/364507-monopattini-elettrici-boom-di-vendite-in-italia\/","title":{"rendered":"Monopattini elettrici: boom di vendite in Italia"},"content":{"rendered":"<h4>Nella prima met\u00e0 dell&#8217;anno il numero di questi piccoli veicoli venduti \u00e8 <strong>quintuplicato rispetto allo stesso periodo del 2018<\/strong>, proponendo un&#8217;ottantina di modelli, omologati per la circolazione stradale<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; \u00c8 boom delle vendite di monopattini elettrici. Secondo le ultime rilevazioni esaminando le vendite e-commerce, nella prima met\u00e0 dell&#8217;anno il numero di questi piccoli veicoli venduti \u00e8 <strong>quintuplicato rispetto allo stesso periodo del 2018<\/strong>, proponendo un&#8217;ottantina di modelli, omologati per la circolazione stradale. Chi viaggia sulle strade senza campanello, fanali anteriori e posteriori e freni su entrambe le ruote potrebbe essere multato. <strong>Le cifre di vendita dimostrano che gli e-scooter sono particolarmente in voga tra gli uomini: solo 13 acquirenti su 100 sono donne.<\/strong> Anche la suddivisione delle classi di et\u00e0 parla da s\u00e9: un acquirente su tre ha fra i 30 e i 39 anni, uno su quattro tra i 20 e i 29 anni e uno su cinque tra i 40 e i 49 anni. Dunque, il tipico proprietario di un e-scooter in Italia \u00e8 un <strong>trentenne di sesso maschile<\/strong>. Come noto non tutti fanno i salti di gioia per la forte diffusione di monopattini: in diverse citt\u00e0 mondiali la loro proliferazione ha portato a seri problemi.<\/p>\n<p>I pedoni si sentono spesso minacciati da chi circola sui marciapiedi o nelle zone pedonali e forti perplessit\u00e0 solleva anche l&#8217;impatto ambientale di questi mezzi oltre a non essere soggetti all\u2019obbligo dell\u2019assicurazione RC. Infatti i <strong>monopattini elettrici sono stati equiparati dalla legge alle biciclette. Basta salire, accelerare e sterzare.<\/strong> Tuttavia i monopattini elettrici sono molto pi\u00f9 pericolosi dal punto di vista del rischio incidenti. Lo rivela uno studio condotto negli Usa e pubblicato da JAMA Surgery, secondo cui sono gli i<strong>nfortuni alla testa quelli pi\u00f9 comuni con il monopattino.<\/strong> I ricercatori dell&#8217;universit\u00e0 di San Francisco hanno analizzato i ricoveri in pronto soccorso per incidenti dovuti agli scooter tra il 2014 e il 2018, confrontando poi i numeri ottenuti con quelli dei traumi dovuti alla bicicletta negli stessi anni.<\/p>\n<p>Nel periodo considerato, spiegano gli autori, il numero totale di incidenti relativi ai monopattini \u00e8 cresciuto del 222%, e quello dei ricoveri del 315%.Dal confronto fra i due mezzi \u00e8 emerso che <strong>quasi un terzo degli utenti dei monopattini ha avuto un trauma alla testa, il cui rischio \u00e8 triplo rispetto a quello dovuto alla bicicletta.<\/strong> Nel 2018 circa un terzo degli incidenti sugli &#8216;e-scooter&#8217; \u00e8 capitato a donne, e la fascia di et\u00e0 pi\u00f9 rappresentata \u00e8 quella tra 18 e 34 anni. Diversi studi, evidenzia <strong>Giovanni D&#8217;Agata<\/strong>, presidente dello \u201cSportello dei Diritti\u201d, hanno dimostrato che <strong>indossare un casco riduce il rischio di traumi.<\/strong> Per tale ragione raccomandiamo di indossarlo e invitiamo anche i produttori dei monopattini a incoraggiarne l&#8217;uso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella prima met\u00e0 dell&#8217;anno il numero di questi piccoli veicoli venduti \u00e8 quintuplicato rispetto allo stesso periodo del 2018, proponendo un&#8217;ottantina di modelli, omologati per la circolazione stradale<\/p>\n","protected":false},"author":22,"featured_media":133818,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-133817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=133817"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133818"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=133817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=133817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=133817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}