{"id":133934,"date":"2020-07-22T13:52:44","date_gmt":"2020-07-22T11:52:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/crosia-installato-primo-defibrillatore-pubblico-sindaco-verso-una-citta-cardio-protetta\/"},"modified":"2023-01-16T18:03:27","modified_gmt":"2023-01-16T17:03:27","slug":"364793-crosia-installato-primo-defibrillatore-pubblico-sindaco-verso-una-citta-cardio-protetta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/364793-crosia-installato-primo-defibrillatore-pubblico-sindaco-verso-una-citta-cardio-protetta\/","title":{"rendered":"Crosia, installato primo defibrillatore pubblico. Sindaco: &#8220;verso una citt\u00e0 cardio-protetta&#8221;"},"content":{"rendered":"<h4>Il prezioso strumento salvavita \u00e8 stato donato alla citt\u00e0 dall&#8217;azienda Caruso, con il sostegno di alcune famiglie<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CROSIA (CS) \u2013 Un nuovo defibrillatore a servizio della comunit\u00e0 di Crosia Mirto e di quanti transitano quotidianamente lungo la Statale 106. <strong>\u00c8 stato installato su Via Nazionale, nei pressi del Comando di Polizia Municipale.<\/strong> Il prezioso strumento salvavita \u00e8 stato donato alla Citt\u00e0 dall&#8217;Agenzia funebre <strong>Alfonso Caruso, con il prezioso sostegno di alcune famiglie.<\/strong> Stamattina la cerimonia di consegna al sindaco <strong>Antonio Russo<\/strong> delle chiavi della bacheca in cui \u00e8 custodito lo strumento medicale che saranno affidate anche ai carabinieri della locale stazione. Alla cerimonia di stamani, presieduta dal primo cittadino, erano presenti anche il titolare dell&#8217;Agenzia funebre, Alfonso Caruso, nonch\u00e9 istruttore salvavita di primo livello; <strong>Carlo Zito<\/strong>, rivenditore ufficiale DAE Italia per la Calabria, e <strong>Pietro Caramia,<\/strong> coordinatore del centro di formazione salvavita &#8220;Missione Cuore&#8221; di Avetrana.<\/p>\n<p>\u00abParte da qui \u2013 ha detto il sindaco Russo, intervenendo alla manifestazione odierna \u2013 <strong>il progetto di Crosia citt\u00e0 cardio-protett<\/strong>a. Un progetto, partito tre anni fa, che coinvolge le aziende del territorio. <strong>Oggi inauguriamo il primo defibrillatore che l&#8217;azienda Caruso mette a disposizione della cittadinanza e di quanti transitano quotidianamente lungo la statale 106.<\/strong> Nei prossimi giorni ne attiveremo un altro offerto da un&#8217;altra associazione operante sul territorio e ci auguriamo che, tempo un anno, potremo vedere installati su tutto il territorio comunale almeno <strong>10 punti di cardio-soccorso.<\/strong> La prevenzione per prevenire le patologie cardiache \u00e8 importante ma \u00e8 essenziale anche sapersi trovare preparati ad intervenire nel momento di massima necessit\u00e0. Ecco perch\u00e9 l&#8217;Amministrazione comunale continua a <strong>sostenere attivamente tutte le attivit\u00e0 di formazione al primo soccorso poste in essere dalla Croce Rossa<\/strong> e da altri enti che operano nella nostra comunit\u00e0\u00bb.<\/p>\n<p>\u00abSiamo felici \u2013 ha aggiunto Alfonso Caruso \u2013 di poter contribuire fattivamente ad un programma di prevenzione e soccorso. E siamo contenti di essere <strong>i primi a Crosia Mirto ad aver installato una bacheca pubblica dove si potranno trovare gli strumenti necessari ad intervenire in caso di un blocco cardiaco.<\/strong> Il defibrillatore installato \u2013 ha spiegato Caruso \u2013 \u00e8 uno strumento sanitario a tutti gli effetti con la peculiarit\u00e0 di essere facilmente utilizzato da chiunque senza il necessario supporto di un operatore sanitario\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prezioso strumento salvavita \u00e8 stato donato alla citt\u00e0 dall&#8217;azienda Caruso, con il sostegno di alcune famiglie<\/p>\n","protected":false},"author":22,"featured_media":133935,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-133934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=133934"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/133934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133935"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=133934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=133934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=133934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}