{"id":134000,"date":"2020-07-23T14:45:05","date_gmt":"2020-07-23T12:45:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/unical-domani-protesta-studenti-contro-rettore-e-terza-rata-i-nostri-diritti-prima-dei-bilanci\/"},"modified":"2023-01-16T18:03:32","modified_gmt":"2023-01-16T17:03:32","slug":"364962-unical-domani-protesta-studenti-contro-rettore-e-terza-rata-i-nostri-diritti-prima-dei-bilanci","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/364962-unical-domani-protesta-studenti-contro-rettore-e-terza-rata-i-nostri-diritti-prima-dei-bilanci\/","title":{"rendered":"Unical, domani protesta studenti contro rettore e terza rata: &#8220;i nostri diritti prima dei bilanci&#8221;"},"content":{"rendered":"<h4><strong>&#8220;Siamo costretti a continuare a sostenere le spese universitarie anche se il nostro Ateneo sia rimasto chiuso per pi\u00f9 di 3 mesi, non erogando la maggior parte dei suoi servizi.<\/strong> Ci sarebbe da ridire anche su quelli erogati, uno su tutti la discussa didattica a distanza, i cui risultati sono stati pessimi&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ARCAVACATA (CS) &#8211; &#8220;Nonostante le richieste di centinaia di studenti, tramite una petizione, &#8211; si legge in una nota &#8211; il Rettore e la Governance dell\u2019Ateneo hanno deciso di tirare dritto e di imporre agli studenti la<strong> terza rata, come se l\u2019epidemia di coronavirus e la seguente crisi economica non ci fossero state.<\/strong> Alle nostre richieste il Rettore ha risposto che<strong> \u201cbisogna far quadrare i bilanci\u201d,<\/strong> motivo per cui il diritto allo studio, sempre pi\u00f9 calpestato negli anni, anche in una situazione emergenziale come quella appena trascorsa, non meriterebbe alcuna tutela<strong>. Ci sarebbe per\u00f2 da chiedersi anche quali bilanci, dato che l&#8217;amministrazione in chiaro della nostra universit\u00e0 \u00e8 ferma, con i bilanci consuntivi, al 2017. <\/strong>Ancora una volta, gli interessi dell&#8217;universit\u00e0-azienda scavalcano i diritti degli studenti, in una situazione paradossale: sembra che al Rettore<strong> non interessi della crisi economica che tante famiglie calabresi stanno vivendo<\/strong>, che certamente non terminer\u00e0 presto.<\/p>\n<p>Infatti, molte famiglie e molti studenti-lavoratori sono in difficolt\u00e0 economiche da mesi e c\u2019\u00e8 gi\u00e0 chi ha perso il posto di lavoro; nonostante ci\u00f2, <strong>siamo costretti a continuare a sostenere le spese universitarie anche se il nostro Ateneo sia rimasto chiuso per pi\u00f9 di 3 mesi, non erogando la maggior parte dei suoi servizi.<\/strong> Ci sarebbe da ridire anche su quelli erogati, uno su tutti la discussa didattica a distanza, i cui risultati sono stati pessimi: l&#8217;Ateneo non si \u00e8 preoccupato minimamente di controllare la reale disponibilit\u00e0 di dispositivi e copertura internet degli studenti, abbandonandoli completamente e non garantendo quindi l&#8217;inclusivit\u00e0 di questo servizio, un grave danno se si considera che l&#8217;universit\u00e0, almeno sulla carta, dovrebbe essere un diritto accessibile a tutti.<\/p>\n<p>Il panorama non \u00e8 certamente roseo e rischia di portare ancora pi\u00f9 studenti ad<strong> abbandonare gli studi per ragioni economiche,<\/strong> dimostrando la natura classista dell\u2019istruzione italiana; a nulla valgono i dati sull\u2019aumento delle iscrizioni tramite TOLC che l\u2019universit\u00e0 si rivendica fieramente <strong>per nascondere le sue mancanze e dare l\u2019impressione che vada tutto bene.<\/strong> Vedremo a settembre quanti saranno realmente gli iscritti e quanti saranno gli studenti costretti ad abbandonare gli studi, senza che il Rettore abbia fatto nulla per aiutarli!<strong> Non vogliamo pi\u00f9 stare a guardare e a subire scelte che mettono a rischio il nostro futuro, vogliamo urlare forte che il diritto allo studio non si tocca e per questo scenderemo in piazza il 24 giugno alle ore 10 sotto il rettorato.<\/strong> I nostri diritti vengono prima dei bilanci!&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Siamo costretti a continuare a sostenere le spese universitarie anche se il nostro Ateneo sia rimasto chiuso per pi\u00f9 di 3 mesi, non erogando la maggior parte dei suoi servizi. Ci sarebbe da ridire anche su quelli erogati, uno su tutti la discussa didattica a distanza, i cui risultati sono stati pessimi&#8221;<\/p>\n","protected":false},"author":21,"featured_media":134001,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-134000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134000"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134001"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}