{"id":134024,"date":"2020-08-08T09:00:23","date_gmt":"2020-08-08T07:00:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/autostrade-domani-e-dopodomani-indetto-lo-sciopero-nazionale\/"},"modified":"2023-01-16T18:03:33","modified_gmt":"2023-01-16T17:03:33","slug":"365018-autostrade-domani-e-dopodomani-indetto-lo-sciopero-nazionale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/365018-autostrade-domani-e-dopodomani-indetto-lo-sciopero-nazionale\/","title":{"rendered":"Autostrade, domani e dopodomani indetto lo sciopero nazionale"},"content":{"rendered":"<h4>Lo hanno annunciato i sindacati: <strong>&#8220;una scelta non facile ma ineludibile<\/strong> perch\u00e8 il sistema sta vivendo un sistema di relazioni industriali a dir poco carente se non inesistente&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA \u2013 Sciopero nazionale di 4 ore del personale delle autostrade il <strong>9 e 10 agosto<\/strong> che interesser\u00e0 nella giornata di <strong>domenica gli addetti all\u2019esazione ai caselli e luned\u00ec il personale tecnico amministrativo<\/strong>. Lo hanno annunciato in conferenza stampa Roberto Moroni Sla Cisal, Paola Avella Ugl Viabilit\u00e0, Marco Verzari Uiltrasporti e Cristina Settimelli Filt Cgil.<\/p>\n<p><strong>Marco Verzari<\/strong> della Uiltrasporti spiega che lo sciopero \u00e8 <strong>\u201cuna scelta non facile ma ineludibile\u201d<\/strong> perch\u00e8 \u201cil sistema sta vivendo un sistema di relazioni industriali a dir poco carente se non inesistente. Questo ha creato una <strong>serie di disastri.<\/strong> La situazione era talmente critica che non potevamo dare una risposta. Abbiamo chiesto incontri alle controparti datoriali e i <strong>risultati non ci sono stati<\/strong> o sono stati inconcludenti\u201d, sottolinea.<\/p>\n<p>Per <strong>Cristina Settimelli<\/strong> della Filt Cgil \u201cl\u2019accordo tra Aspi e governo lascia una serie di incognite.<strong> Siamo preoccupati: ci manca l\u2019interlocuzione con l\u2019esecutivo.<\/strong> L\u2019accordo- osserva- \u00e8 preferibile alla revoca della concessione che avrebbe aperto uno scenario inimmaginabile anche dal punto di vista del personale. <strong>Resta per\u00f2 la preoccupazione per 14 mila addetti, considerando tutte le societ\u00e0 e l\u2019indotto<\/strong>\u201d. Insomma \u201cci sono una serie di cose non chiare e una serie di criticit\u00e0\u201d, per cui si rende necessario \u201c<strong>un confronto urgente<\/strong>, che immagino sar\u00e0 a settembre ma noi siamo disponibili anche pri08ma con il governo nell\u2019interesse del Paese\u201d, conclude la sindacalista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo hanno annunciato i sindacati: &#8220;una scelta non facile ma ineludibile perch\u00e8 il sistema sta vivendo un sistema di relazioni industriali a dir poco carente se non inesistente&#8221;<\/p>\n","protected":false},"author":22,"featured_media":134025,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-134024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134024"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134025"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}