{"id":134254,"date":"2020-07-30T04:30:54","date_gmt":"2020-07-30T02:30:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/gli-studenti-internazionali-dellunical-ospiti-del-comune-di-domanico\/"},"modified":"2023-01-16T18:03:49","modified_gmt":"2023-01-16T17:03:49","slug":"365743-gli-studenti-internazionali-dellunical-ospiti-del-comune-di-domanico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/365743-gli-studenti-internazionali-dellunical-ospiti-del-comune-di-domanico\/","title":{"rendered":"Gli studenti internazionali dell\u2019Unical ospiti del Comune di Domanico"},"content":{"rendered":"<h4>Domanico accoglie gli studenti internazionali dell\u2019Universit\u00e0 della Calabria grazie alla collaborazione fra l\u2019Associazione culturale Entropia e l\u2019Associazione Cascina Way<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>DOMANICO (CS) &#8211; Domani, venerd\u00ec 31 luglio, gli studenti saranno ospiti dell\u2019amministrazione comunale di Domanico, per una visita guidata nel borgo e un pranzo di convivialit\u00e0. La partenza \u00e8 prevista alle ore 9 dalle pensiline del Campus, con il pulmino messo a disposizione dal Comune e le auto dello staff di Entropia. <strong>La camminata nel centro storico<\/strong> sar\u00e0 guidata da Marina Muto, consigliera comunale di Domanico, con il supporto multilinguistico delle volontarie del Servizio Civile Universale.<\/p>\n<p><strong> Tappa obbligata della visita sar\u00e0 la Motta<\/strong>, primo nucleo insediativo del paese. Il borgo si erge su una rupe rocciosa molto suggestiva e panoramica e vi si accede tramite una serie di gradoni scavati nella roccia, fiancheggiati da abitazioni accorpate, tra le quali si trovano resti, ruderi e testimonianze di antichi insediamenti umani. Al termine dell\u2019escursione, ai partecipanti sar\u00e0 offerta una degustazione di prodotti tipici locali, accompagnata da musica e socialit\u00e0.<\/p>\n<p>L\u2019Urban Trekking \u00e8 una delle attivit\u00e0 di \u201c<strong>Studenti senza frontiere 2\u201d<\/strong>, il progetto di Servizio civile universale dell\u2019associazione culturale Entropia con sede all\u2019Unical. L\u2019attivit\u00e0, gi\u00e0 sperimentata lo scorso anno nell\u2019ambito della prima annualit\u00e0 del progetto, \u00e8 un modo semplice e diretto per scoprire le bellezze spesso sconosciute del territorio calabrese da parte degli studenti dell\u2019Unical, promuovendo lo scambio interculturale e portando un ambiente internazionale nei piccoli paesi e nelle aree interne. Stimolare le comunit\u00e0 locali innestando pratiche di condivisione fra culture diverse rappresenta il modo migliore per costruire una societ\u00e0 pi\u00f9 aperta e inclusiva, oltre che una concreta azione di promozione del territorio e dei paesini calabresi in particolare.<\/p>\n<p>Il trekking chiude la prima fase del progetto, che ha visto lo staff di Entropia e le volontarie del Servizio Civile impegnati anche nel periodo pi\u00f9 critico della pandemia, offrendo servizi aggiuntivi e di supporto alla comunit\u00e0 internazionale del Campus, <strong>nel rispetto delle misure di prevenzione del contagio da Covid19.<\/strong> Con la ripresa della programmazione culturale, l\u2019associazione ha riportato gradualmente la socialit\u00e0 nel Campus, prediligendo gli spazi all\u2019aperto e offrendo agli studenti rimasti negli alloggi la possibilit\u00e0 di incontrarsi e sentirsi meno isolati. <strong>La gita a Domanico, completamente gratuita, sar\u00e0 altres\u00ec un modo per salutare gli associati prima delle vacanze estive.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-365745 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/07\/DOMANICO1.jpg\" alt=\"\" width=\"425\" height=\"974\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domanico accoglie gli studenti internazionali dell\u2019Universit\u00e0 della Calabria grazie alla collaborazione fra l\u2019Associazione culturale Entropia e l\u2019Associazione Cascina Way<\/p>\n","protected":false},"author":42,"featured_media":134255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-134254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134254"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134255"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}