{"id":134436,"date":"2020-07-31T13:45:45","date_gmt":"2020-07-31T11:45:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragico-incidente-a-montegiordano-muore-un-24enne-ferito-gravemente-un-23enne\/"},"modified":"2023-01-16T18:04:01","modified_gmt":"2023-01-16T17:04:01","slug":"366144-tragico-incidente-a-montegiordano-muore-un-24enne-ferito-gravemente-un-23enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/366144-tragico-incidente-a-montegiordano-muore-un-24enne-ferito-gravemente-un-23enne\/","title":{"rendered":"Tragico incidente a Montegiordano: muore un 24enne, ferito gravemente un 23enne"},"content":{"rendered":"<h4>Un triste bilancio quello dell&#8217;incidente avvenuto questa notte, che ha visto protagonisti due ragazzi che <strong>stavano viaggiando in direzione sud quando, all\u2019altezza della prima delle tre gallerie, il conducente ha perso il controllo del mezzo<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MONTEGIORDANO (CS) &#8211; Tragico incidente lungo la superstrada E 90 a Montegiordano. A farne le spese un <strong>giovane di soli 24 anni, gravemente ferito in prognosi riservata l&#8217;altro giovane che si trovava in auto con lui, di 23 anni.<\/strong> Un triste bilancio quello dell&#8217;incidente avvenuto questa notte, che ha visto protagonisti due ragazzi che <strong>stavano viaggiando in direzione sud quando, all\u2019altezza della prima delle tre gallerie, il conducente ha perso il controllo del mezzo.<\/strong> Ancora restano da capire le cause esatte del terribile impatto. Sul posto sono intervenuti gli agenti della Polstrada del distaccamento di Trebisacce per i rilievi del caso e il personale sanitario del 118.<\/p>\n<p>Secondo le prime ricostruzioni \u00e8 emerso che <strong>l&#8217;auto ha prima sbattuto contro il cordolo e la galleria stessa, per poi concludere la sua corsa contro la parte posteriore di un autobus di linea Puglia-Sicilia che precedeva il mezzo<\/strong> nello stesso senso di marcia. <strong>Il conducente dell\u2019auto, V. J. B., 24 anni nato e residente te ad Avellino, \u00e8 deceduto sull\u2019ambulanza<\/strong> del 118 di Trebisacce che lo stava portando nell\u2019ospedale di Rossano, mentre <strong>il passeggero, L. G., 23enne nato e residente ad Avellino, \u00e8 stato trasferito con altra ambulanza presso l\u2019ospedale lucano di Policoro<\/strong>. Il giovane che ha diversi traumi \u00e8 prognosi riservata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un triste bilancio quello dell&#8217;incidente avvenuto questa notte, che ha visto protagonisti due ragazzi che stavano viaggiando in direzione sud quando, all\u2019altezza della prima delle tre gallerie, il conducente ha perso il controllo del mezzo<\/p>\n","protected":false},"author":22,"featured_media":134437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-134436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134436"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134437"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}