{"id":134468,"date":"2020-08-01T06:25:07","date_gmt":"2020-08-01T04:25:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestrate-due-opere-edilizie-abusive-a-longobucco-e-pietrapaola-denunciate-due-persone\/"},"modified":"2023-01-16T18:04:04","modified_gmt":"2023-01-16T17:04:04","slug":"366257-sequestrate-due-opere-edilizie-abusive-a-longobucco-e-pietrapaola-denunciate-due-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/366257-sequestrate-due-opere-edilizie-abusive-a-longobucco-e-pietrapaola-denunciate-due-persone\/","title":{"rendered":"Sequestrate due opere edilizie abusive a Longobucco e Pietrapaola: denunciate due persone"},"content":{"rendered":"<h4>Una delle due aree era <strong>vincolata idrogeologicamente. In entrambi i casi la realizzazione dell&#8217;opera <\/strong>\u00e8 avvenuta senza permesso a costruire<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PIETRAPAOLA (CS) \u2013 I militari della Stazione Carabinieri Forestale di Rossano, durante un\u2019attivit\u00e0 di controlli mirata alla prevenzione e alla repressione delle violazioni in materia urbanistica e paesaggistica, hanno accertato la realizzazione di<strong> due opere edilizie abusive ricadenti nei comuni di Pietrapaola e Longobucco.<\/strong> In particolare i militari, durante un servizio di controllo congiunto con la Stazione Carabinieri di Mandatoriccio, hanno rilevato la <strong>realizzazione abusiva in localit\u00e0 \u201cDestra del Palazzo\u201d a Pietrapaola, area questa vincolata idrogeologicamente, di una platea in cemento armato con tettoia di alluminio sostenuta da pilastri in acciaio,<\/strong> la cui realizzazione \u00e8 avvenuta senza permesso a costruire.<\/p>\n<p>Altra opera abusiva \u00e8 stata rinvenuta in localit\u00e0<strong> Pantano di Longobuicco<\/strong> dove i Carabinieri Forestale hanno posto sotto sequestro<strong> un manufatto edile realizzato con blocchi in cemento e su di esso posata una copertura in lamiera aperta<\/strong>. In entrambi i casi alla luce delle evidenze emerse, oltre al sequestro ed alle previste sanzioni e, \u00e8 scattata la denuncia in stato di libert\u00e0 alla Procura della Repubblica di Castrovillari a carico di due persone, ritenute responsabili dei lavori abusivi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una delle due aree era vincolata idrogeologicamente. In entrambi i casi la realizzazione dell&#8217;opera \u00e8 avvenuta senza permesso a costruire<\/p>\n","protected":false},"author":22,"featured_media":134469,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-134468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134468"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134469"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}