{"id":134544,"date":"2020-08-03T10:28:36","date_gmt":"2020-08-03T08:28:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spaccio-di-droga-in-sila-arrestata-coppia-di-camigliatello\/"},"modified":"2023-01-16T18:04:08","modified_gmt":"2023-01-16T17:04:08","slug":"366397-spaccio-di-droga-in-sila-arrestata-coppia-di-camigliatello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/366397-spaccio-di-droga-in-sila-arrestata-coppia-di-camigliatello\/","title":{"rendered":"Spaccio di droga in Sila, arrestata coppia di Camigliatello"},"content":{"rendered":"<h4>Rinvenuti all\u2019interno dell\u2019abitazione <strong>125 grammi di cocaina e 450 grammi di marijuana<\/strong>, un bilancino di precisione e materiale per il confezionamento<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CAMIGLIATELLO SILACO (CS)- I carabinieri hanno tratto in arresto per il reato di detenzione ai fini di spaccio di sostanze stupefacenti un <strong>uomo ed una donna, entrambi 39enni di Camigliatello Silano<\/strong>, e denunciato un 21enne in stato di libert\u00e0. L\u2019operazione \u00e8 scattata alle prime luci dell\u2019alba di sabato, quando il personale operante, dopo aver cinturato l\u2019abitazione dei due 39enni, hanno fatto irruzione sorprendendoli con lo stupefacente. Nel corso dell\u2019incursione, la donna ha gettato parte dello stupefacente dalla finestra, che \u00e8 stato poi recuperato dai militari disposti a sorvegliare le vie di fuga. All\u2019interno dell\u2019abitazione oltre alla donna era presente il compagno, che \u00e8 stato fermato prima che riuscisse a disfarsi di un altro involucro contenente della marijuana.<\/p>\n<p>Nel corso della perquisizione domiciliare eseguita con il prezioso ausilio dell\u2019unit\u00e0 cinofila dello Squadrone dei Cacciatori di Calabria, sono stati rinvenuti <strong>125 grammi di cocaina e 450 grammi di marijuana<\/strong>, un bilancino di precisione e materiale per il confezionamento. Dalle analisi eseguite presso il laboratorio del Comando Provinciale di Vibo Valentia \u00e8 emerso che lo stupefacente avrebbe garantito ai due fermati circa 800 dosi di cocaina e 1.500 di marijuana. La droga immessa sul mercato aveva un valore di circa 60 mila euro.Gli arrestati su disposizione del magistrato di turno presso la Procura della Repubblica di Cosenza sono stati sottoposti al regime degli arresti domiciliari in attesa del rito direttissimo.<\/p>\n<p>Nel corso di un\u2019ulteriore perquisizione domiciliare nell\u2019abitazione di 21enne, sono stati rinvenuti altri di 4 grammi di sostanza stupefacente del tipo marijuana ed un bilancino di precisione. Il giovane \u00e8 stato denunciato all&#8217;autorit\u00e0 giudiziaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rinvenuti all\u2019interno dell\u2019abitazione 125 grammi di cocaina e 450 grammi di marijuana, un bilancino di precisione e materiale per il confezionamento<\/p>\n","protected":false},"author":56,"featured_media":134545,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-134544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134544"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134545"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}