{"id":134702,"date":"2020-08-16T09:00:47","date_gmt":"2020-08-16T07:00:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/unical-pubblicato-il-bando-dammissione-per-le-lauree-magistrali\/"},"modified":"2023-01-16T18:04:18","modified_gmt":"2023-01-16T17:04:18","slug":"366682-unical-pubblicato-il-bando-dammissione-per-le-lauree-magistrali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/366682-unical-pubblicato-il-bando-dammissione-per-le-lauree-magistrali\/","title":{"rendered":"Unical, pubblicato il bando d&#8217;ammissione per le lauree magistrali"},"content":{"rendered":"<h4>Sar\u00e0 possibile presentare domanda entro il 18 settembre. I corsi disponibili sono 43, tre dei quali erogati interamente in lingua inglese<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ARCAVACATA (CS) &#8211; Dal 27 agosto al 18 settembre sar\u00e0 possibile presentare domanda d&#8217;ammissione per i corsi di laurea magistrale dell&#8217;Universit\u00e0 della Calabria. <strong>Il bando e gli allegati relativi ai dipartimenti sono gi\u00e0 disponibili nella sezione \u201cAmmissione\u201d del portale d&#8217;ateneo.<\/strong> I corsi di laurea magistrale che compongono l&#8217;offerta formativa dell&#8217;Unical sono<strong> 43, tre dei quali erogati in lingua inglese<\/strong> (Computer Engineering for the Internet of Things,Computer Science, Finance and Insurance). All&#8217;ammissione possono partecipare studentesse e studenti che abbiano gi\u00e0 la laurea triennale, ma molti corsi danno la possibilit\u00e0 di iscriversi anche prima di aver conseguito il titolo, nel caso in cui la fine degli studi sia prevista a breve.<\/p>\n<p><strong>COME ISCRIVERSI<\/strong> &#8211; Per presentare domanda d\u2019ammissione, \u00e8 necessario registrarsi sul portale Esse 3 dell\u2019Unical (solo nel caso in cui non si abbiano gi\u00e0 le credenziali). Una volta effettuato l\u2019accesso al portale, occorre selezionare dal menu \u2018Segreteria\u2019 e poi \u2018Bandi d\u2019ammissione\u2019. A quel punto si potr\u00e0 compilare la domanda.<strong> Il termine ultimo \u00e8 il 18 settembre, entro le 12<\/strong>. I candidati vincitori avranno 6 giorni di tempo, dalla pubblicazione delle graduatorie definitive, per immatricolarsi pagando la prima rata di 16,50 euro. Per gli studenti che si iscrivono con riserva, in attesa di conseguire il titolo, l&#8217;immatricolazione dovr\u00e0 essere perfezionata dopo la laurea. Per verificare i requisiti di ammissione dei singoli corsi di laurea e le date di pubblicazione delle graduatorie si consiglia di consultare gli allegati dei dipartimenti. I posti che resteranno vacanti al termine dell&#8217;immatricolazione saranno assegnati scorrendo la graduatoria.<\/p>\n<p><strong>TASSE E AGEVOLAZIONI<\/strong> &#8211; Da quest\u2019anno, per come previsto dai nuovi provvedimenti ministeriali, <strong>la no tax area \u00e8 innalzata a 20mila euro<\/strong>: gli studenti con i requisiti previsti dalla legge appartenenti a nuclei familiari con un ISEE DSU entro questa soglia non pagheranno il contributo annuale. Previste anche ulteriori <strong>agevolazioni per chi ha un ISEE DSU compreso tra 20mila e 30mila euro, con riduzioni che andranno dall\u201980 al 10 per cento.<\/strong> Per maggiori informazioni \u00e8 possibile consultare il nuovo regolamento Tasse e contributi. Gli studenti, in regola con la carriera, che conseguono la laurea triennale entro il 31 dicembre 2020 hanno diritto <strong>all\u2019esonero totale del contributo annuale<\/strong> se si iscrivono a un corso magistrale dell\u2019Unical nell\u2019anno accademico 2020\/2021. Gli studenti, sempre in regola con la carriera, che entro il 31 dicembre 2020 completano gli esami previsti dal proprio piano di studi (esclusa la prova finale) usufruiscono invece di una riduzione del <strong>50 per cento del contributo.<\/strong><\/p>\n<p><strong>DIRITTO ALLO STUDIO<\/strong> \u2013 I nuovi iscritti ai corsi di laurea magistrale potranno presentare <strong>richiesta per la borsa di studio entro il 30 ottobre.<\/strong> La domanda \u00e8 disponibile di norma almeno 30 giorni prima della scadenza. Per poter partecipare al concorso per l\u2019assegnazione di borse e servizi l\u2019ISEE-DSU del proprio nucleo familiare non deve superare i<strong> 23mila 626,32 euro<\/strong>, mentre il limite massimo per l\u2019ISPE \u00e8 fissato a <strong>51mila 361,58 euro<\/strong>. Per maggiori informazioni, consultare il bando per il diritto allo studio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 possibile presentare domanda entro il 18 settembre. I corsi disponibili sono 43, tre dei quali erogati interamente in lingua inglese<\/p>\n","protected":false},"author":22,"featured_media":134703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-134702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134702"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134703"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}