{"id":134816,"date":"2020-08-08T17:00:56","date_gmt":"2020-08-08T15:00:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/crosia-pronto-il-piano-mare-al-via-una-nuova-vision-turistica\/"},"modified":"2023-01-16T18:04:26","modified_gmt":"2023-01-16T17:04:26","slug":"366898-crosia-pronto-il-piano-mare-al-via-una-nuova-vision-turistica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/366898-crosia-pronto-il-piano-mare-al-via-una-nuova-vision-turistica\/","title":{"rendered":"Crosia, pronto il Piano Mare: al via una nuova vision turistica"},"content":{"rendered":"<h4>Tredici nuovi spazi da destinare ad attivit\u00e0 commerciali di cui cinque dedicati alla grande ricettivit\u00e0; nuovi spazi per la cultura e lo spettacolo; piste ciclabili e dedicate agli sport su rotelle; valorizzazione delle aree verdi e dei parchi fluviali<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CROSIA (CS) \u2013 Piano Mare, il governo Russo pronto a varare il pi\u00f9 importante e ambizioso progetto di urbanizzazione e sviluppo turistico della storia del comune traentino. Tredici nuovi spazi da destinare ad attivit\u00e0 commerciali di cui cinque dedicati alla grande ricettivit\u00e0; nuovi spazi per la cultura e lo spettacolo; piste ciclabili e dedicate agli sport su rotelle; valorizzazione delle aree verdi e dei parchi fluviali. <strong>L&#8217;Amministrazione civica crea una nuova vision per l&#8217;area di Centofontane destinata a diventare una vera e propria cittadella turistica in riva al mare.<\/strong> Questo nella prospettiva ancora pi\u00f9 ambiziosa di poter avviare la progettazione esecutiva del nuovo porticciolo del Tr\u00e0es per il diportismo. \u00c8 quanto fanno sapere il sindaco <strong>Antonio Russo<\/strong> e l&#8217;assessore all&#8217;Urbanistica, <strong>Giovanni Greco<\/strong>, che a termine della fase tecnica di progettazione annunciano l&#8217;ormai imminente apertura delle procedure per l&#8217;assegnazione delle aree del nuovo Piano Mare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-366899 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/08\/RUSSO-GRECO.jpeg\" alt=\"\" width=\"660\" height=\"425\" title=\"\"><\/p>\n<p>\u00abUn progetto ambizioso \u2013 dice Greco \u2013 che finalmente metter\u00e0 mano ad un&#8217;area, quella di <strong>Centofontane, tra le pi\u00f9 belle e funzionali del litorale ionico della Sibaritide<\/strong> ma che al momento sfrutta al minimo le sue grandissime potenzialit\u00e0 sia in termini di spazi che di offerta turistico-ricettiva. Saranno assegnate \u2013 spiega l&#8217;assessore all&#8217;urbanistica \u2013 <strong>8 nuove aree da destinare ad attivit\u00e0 ricettive.<\/strong> Ogni area avr\u00e0 dimensioni che variano dai 650 a 1.600 metri quadrati. Non solo. Nel progetto sono previste anche<strong> 5 aree destinate a possibile trasformazione che potranno essere destinate alla realizzazione di alberghi o di altre moderne strutture ricettive,<\/strong> con volumetrie importanti che spaziano da un minimo di 2.700 metri quadri ad un massimo di 2 ettari. Un&#8217;opportunit\u00e0 per l&#8217;imprenditoria turistica che volesse investire a due passi dal mare in un contesto urbanistico comune gi\u00e0 solidificato\u00bb.<\/p>\n<p>\u00abSono questi i progetti \u2013 commenta il sindaco Russo \u2013 che contribuiscono ad innalzare la qualit\u00e0 della vita nel nostro territorio, a rendere questa citt\u00e0 appetibile e funzionale agli investimenti. <strong>Progettare una citt\u00e0 moderna e al passo con i tempi \u00e8 una soluzione per far fronte alla crisi e per creare nuove opportunit\u00e0 di lavoro.<\/strong> Non \u00e8 un caso se negli ultimi cinque anni il comune di Crosia \u00e8 stato l&#8217;unico in tutto il comprensorio ionico a far registrare un incremento demografico e, finalmente, anche una presenza maggiore di giovani che hanno deciso di scommettere su questo territorio rinunciando ad emigrare. E questo ci incoraggia a programmare, progettare e mettere in cantiere<strong> iniziative che mirano ad accrescere l&#8217;attrattivit\u00e0 della nostra terra.<\/strong> Nel 2014 l&#8217;area di Centofontane era in condizioni pietose, come un diamante gettato nel letame. Tra mille difficolt\u00e0 economiche ma con tantissimo entusiasmo l&#8217;abbiamo riqualificata e resa subito vivibile.<strong> Sono arrivate le bandiere verdi<\/strong>. Sono arrivati i primi turisti, attratti dalla bellezza della nostra costa e dai servizi che si riescono ad offrire. E ancora oggi, basta farsi un giro sulle nostre spiagge per notare concretamente, anche nell&#8217;attuale momento di crisi ed emergenza pandemica, quanti turisti hanno scelto di trascorrere le loro vacanze qui da noi. Potevamo fermarci e godere dei risultati finora ottenuti, che sono storici. Invece, consapevoli delle enormi potenzialit\u00e0 della nostra area costiera, <strong>vogliamo fare di pi\u00f9 per trasformare questo piccolo angolo di Calabria in una delle zone di grande interesse turistico<\/strong>. La riuscita di questo progetto, ovviamente, non dipende solo dalla progettazione pubblica ma \u2013 precisa il Primo cittadino \u2013 anche dalla capacit\u00e0 di investimento dei privati\u00bb.<\/p>\n<p>\u00abSono ormai lontani i tempi &#8211; aggiunge &#8211; in cui trovammo una citt\u00e0 ripiegata su se stessa, senza prospettiva e con i fari spenti. Oggi stiamo potenziando tutti i servizi e li stiamo portando li dove non c&#8217;erano. Abbiamo rivoltato il<strong> settore ambiente garantendo una proficua ed efficace campagna di gestione dei rifiuti<\/strong> e mettendo mani ad un altro progetto storico che \u00e8 il potenziamento del depuratore. Abbiamo ridato <strong>dignit\u00e0 a tutti gli edifici scolastici cittadini.<\/strong> Abbiamo <strong>rifatto strade<\/strong>, rilanciato le prospettive del centro storico, mettendolo in sicurezza e avviando la riqualificazione di <strong>palazzi storici.<\/strong> Abbiamo praticamente aperto il grande cantiere Crosia per una citt\u00e0 in continua evoluzione. E a quei pochissimi \u2013 conclude Russo &#8211; che dicono che siamo una citt\u00e0 al buio voglio ricordare che a giorni partir\u00e0 anche un altro grande progetto di riqualificazione energetica con il potenziamento di tutto <strong>l&#8217;impianto di illuminazione<\/strong> pubblica. Pi\u00f9 luce di cos\u00ec!\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tredici nuovi spazi da destinare ad attivit\u00e0 commerciali di cui cinque dedicati alla grande ricettivit\u00e0; nuovi spazi per la cultura e lo spettacolo; piste ciclabili e dedicate agli sport su rotelle; valorizzazione delle aree verdi e dei parchi fluviali<\/p>\n","protected":false},"author":22,"featured_media":134817,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-134816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134816"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134817"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}