{"id":134906,"date":"2020-08-10T16:06:59","date_gmt":"2020-08-10T14:06:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/otto-studenti-cosentini-tornati-dalla-grecia-sottoposti-a-tampone-uno-e-positivo\/"},"modified":"2023-01-16T18:04:32","modified_gmt":"2023-01-16T17:04:32","slug":"367074-otto-studenti-cosentini-tornati-dalla-grecia-sottoposti-a-tampone-uno-e-positivo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/367074-otto-studenti-cosentini-tornati-dalla-grecia-sottoposti-a-tampone-uno-e-positivo\/","title":{"rendered":"Otto studenti cosentini tornati dalla Grecia sottoposti a tampone. Uno \u00e8 positivo"},"content":{"rendered":"<h4>I ragazzi, tutti 19enni, sono tornati sabato scorso da una vacanza a Corf\u00f9. Per adesso uno di loro, residente a Castrolibero, \u00e8 risultato positivo al coronavirus. Gli esiti dei tamponi a tutti gli altri ragazzi sono attesi nelle prossime ore <!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; <strong>Otto studenti cosentini, <\/strong>diciannovenni, tornati da Corf\u00f9 sabato scorso sono stati sottoposti ai tamponi rinofaringei da parte della task dell\u2019Asp di Cosenza. <strong>Per ora uno di loro, residente a Castrolibero, \u00e8 risultato positivo al Covid-19<\/strong>. Gli altri tamponi saranno processati nelle prossime ore. Qualcuno dei ragazzi comunque mostra lievi sintomi riconducibili al Covid-19.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10992\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-367082\" src=\"https:\/\/quicosenza.it\/news\/10992\" alt=\"\" width=\"566\" height=\"337\" title=\"\"><\/a><\/p>\n<p>Tutti i giovani, insieme alle famiglie, si trovano in isolamento domiciliare. Intanto, i sanitari dell\u2019Asp Bruzia hanno subito avviato<strong> la ricostruzione della catena dei contatti<\/strong>. Secondo quanto si apprende, uno dei ragazzi si \u00e8 presentato spontaneamente al Dipartimento di prevenzione, igiene e tutela della salute, perch\u00e9 venuto a conoscenza di casi di positivit\u00e0 all&#8217;interno del gruppo partito per la vacanza in Grecia e che comprendeva oltre <strong>150 studenti italiani<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I ragazzi, tutti 19enni, sono tornati sabato scorso da una vacanza a Corf\u00f9. Per adesso uno di loro, residente a Castrolibero, \u00e8 risultato positivo al coronavirus. Gli esiti dei tamponi a tutti gli altri ragazzi sono attesi nelle prossime ore<\/p>\n","protected":false},"author":55,"featured_media":134907,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-134906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134906"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134907"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}