{"id":134954,"date":"2020-08-11T18:10:16","date_gmt":"2020-08-11T16:10:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrovillari-umiliano-invalido-e-gli-incendiano-casa-nel-branco-anche-due-minori\/"},"modified":"2023-01-16T18:04:36","modified_gmt":"2023-01-16T17:04:36","slug":"367193-castrovillari-umiliano-invalido-e-gli-incendiano-casa-nel-branco-anche-due-minori","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/367193-castrovillari-umiliano-invalido-e-gli-incendiano-casa-nel-branco-anche-due-minori\/","title":{"rendered":"Castrovillari, umiliano invalido e gli incendiano casa. Nel branco anche due minori"},"content":{"rendered":"<h4>Una vera e propria spedizione punitiva e vigliacca nei confronti di una persona invalida che vive sola in un&#8217;abitazione del centro del Pollino. Lo hanno colpito in casa con getti d\u2019acqua mentre stava riposando e poi hanno dato fuoco all\u2019abitazione. E non sarebbe stata la prima aggressione subita<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>CASTROVILLARI (CS) &#8211; Una sorta di spedizione punitiva, crudele e insensata. Un vero e proprio raid, che avrebbe potuto avere conseguenze drammatiche, quello di cui si sarebbero resi protagonisti cinque giovani &#8211; tre appena maggiorenni che sono stati arrestati, e due minori &#8211; accusati di a<strong>vere preso di mira con inaudita cattiveria un invalido civile con problemi psichici.<\/strong> E&#8217; accaduto a Castrovillari in una notte d&#8217;estate. In carcere sono finiti S. B. C. di 18 anni, A.S. e M. S entrambi 19enni, ai quali i carabinieri hanno notificato un&#8217;ordinanza di custodia cautelare emessa dal Gip del Tribunale di Castrovillari su richiesta della Procura, con l&#8217;accusa di incendio e violazione di domicilio.<\/p>\n<p>Gli altri due ragazzi, non ancora maggiorenni, sono stati raggiunti, per gli stessi reati, dalla misura cautelare del collocamento in comunit\u00e0: un provvedimento emesso dal Gip del Tribunale dei minorenni di Catanzaro.<strong> Vittima del branco \u00e8 un sessantenne con problemi di salute<\/strong> che vive da solo in una casa del centro storico della citt\u00e0 del Pollino diventato bersaglio di un&#8217;azione quasi da &#8220;<strong>Arancia Meccanica<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/11003\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-186609\" src=\"https:\/\/quicosenza.it\/news\/11003\" alt=\"\" width=\"533\" height=\"383\" title=\"\"><\/a><\/p>\n<p>A fare scattare le indagini dei militari della compagnia di Castrovillari, avviate il 2 agosto, <strong>l&#8217;incendio scoppiato nell&#8217;abitazione del pensionato<\/strong>. Da quell&#8217;episodio gli investigatori dell&#8217;arma sono partiti per ricostruire quanto accaduto arrivando a dare un volto e un nome agli autori di un raid di cui al momento non si conoscono le ragioni. Secondo quanto \u00e8 emerso, per\u00f2, i giovanissimi componenti del branco, dopo essere entrati nello stabile al piano terra dove l&#8217;uomo vive, approfittando della porta d&#8217;ingresso dell&#8217;appartamento non perfettamente chiusa dall&#8217;interno, si sarebbero accaniti contro la vittima predestinata che stava dormendo<strong> lanciandogli addosso dei getti d&#8217;acqua che lo hanno svegliato di soprassalto<\/strong>.<\/p>\n<p>Non soddisfatti, prima di allontanarsi velocemente facendo perdere le proprie tracce tra le viuzze del centro storico della citt\u00e0,<strong> i cinque avrebbero dato fuoco, usando fogli di giornale, all&#8217;abitazione.<\/strong> Il rogo che ne \u00e8 scaturito \u00e8 stato spento dai vigili del fuoco. L&#8217;uomo, dopo essersi svegliato a seguito delle secchiate d&#8217;acqua, \u00e8 riuscito ad uscire di casa prima che l&#8217;intero appartamento prendesse fuoco. Il pensionato ha poi raccontato di aver subito gi\u00e0 in precedenza comportamenti simili e di<strong> essere stato bersaglio di getti d&#8217;acqua da parte di ragazzi<\/strong> che per\u00f2, in quella specifica occasione, non era riuscito ad identificare. L&#8217;episodio, che ha provocato <strong>sconforto e indignazione tra i cittadini di Castrovillari,<\/strong> riporta alla mente fatti analoghi e anche pi\u00f9 cruenti avvenuti nei mesi e negli anni scorsi. A cominciare da quello di Manduria, in Puglia, dove l&#8217;anno scorso <strong>una baby gang venne fermata per aver aggredito e pestato a morte un disabile<\/strong> arrivando perfino a filmare le gesta con il telefonino. A maggio un diciannovenne e un ventitreenne sono stati condannati a 10 anni di reclusione, un altro ventitreenne a 8 anni e 8 mesi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vera e propria spedizione punitiva e vigliacca nei confronti di una persona invalida che vive sola in un&#8217;abitazione del centro del Pollino. Lo hanno colpito in casa con getti d\u2019acqua mentre stava riposando e poi hanno dato fuoco all\u2019abitazione. E non sarebbe stata la prima aggressione subita<\/p>\n","protected":false},"author":55,"featured_media":134955,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-134954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=134954"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/134954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134955"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=134954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=134954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=134954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}