{"id":135190,"date":"2020-08-18T08:24:49","date_gmt":"2020-08-18T06:24:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/conferimenti-limitati-a-bucita-e-a-rende-ecoross-questione-rifiuti-cronica\/"},"modified":"2023-01-16T18:04:52","modified_gmt":"2023-01-16T17:04:52","slug":"367658-conferimenti-limitati-a-bucita-e-a-rende-ecoross-questione-rifiuti-cronica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/367658-conferimenti-limitati-a-bucita-e-a-rende-ecoross-questione-rifiuti-cronica\/","title":{"rendered":"Conferimenti limitati a Bucita e a Rende, Ecoross: &#8220;questione rifiuti cronica&#8221;"},"content":{"rendered":"<h4>L\u2019azienda sta cercando di fronteggiare al meglio la situazione, compromessa dai conferimenti limitati, anche a fronte del surplus di produzione di rifiuti fisiologico durante la stagione estiva<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Ecoross, societ\u00e0 che si occupa del servizio di Igiene Urbana in vari comuni afferenti agli impianti finali di trattamento di Bucita, a Corigliano Rossano, e di Calabra Maceri e Servizi spa, a Rende, informa che permangono <strong>disagi e disservizi<\/strong> nella raccolta dei rifiuti sui territori per <strong>cause non imputabili n\u00e9 all\u2019azienda n\u00e9 alle Amministrazioni Comunali<\/strong> che, per quanto di propria competenza, si stanno adoperando al meglio senza lesinare sforzi e sacrifici.<\/p>\n<p>&#8220;Considerate le sopraggiunte e perduranti limitazioni nei conferimenti, anche a fronte di un surplus di rifiuti collegato al fisiologico incremento demografico che si verifica durante la stagione estiva, in particolare nel mese di agosto, vi \u00e8 uno scarto ingente tra rifiuti prodotti e rifiuti conferibili. Il che si traduce anche in ritardi nei servizi di raccolta dei rifiuti solidi urbani. <strong>Nonostante gli sforzi messi in campo<\/strong>, sia da parte dell\u2019azienda sia da parte degli Enti comunali, la <strong>problematica permane&#8221;<\/strong>.<\/p>\n<p>Ecoross sta cercando di fronteggiare al meglio la situazione con uno straordinario impiego di uomini e mezzi, ma le difficolt\u00e0 nei conferimenti, divenute quasi ordinarie, rischiano di compromettere i risultati di un lavoro portato avanti con impegno e costanza. Al fine di scongiurare ulteriori e pi\u00f9 gravi disagi si auspica una<strong> celere e definitiva risoluzione della ormai cronica \u201cquestione rifiuti\u201d in ambito regionale.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019azienda sta cercando di fronteggiare al meglio la situazione, compromessa dai conferimenti limitati, anche a fronte del surplus di produzione di rifiuti fisiologico durante la stagione estiva<\/p>\n","protected":false},"author":42,"featured_media":135191,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-135190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=135190"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/135191"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=135190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=135190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=135190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}