{"id":135192,"date":"2020-08-23T09:00:15","date_gmt":"2020-08-23T07:00:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-riprendono-le-crociere-tamponi-e-nuovi-protocolli-di-sicurezza\/"},"modified":"2023-01-16T18:04:52","modified_gmt":"2023-01-16T17:04:52","slug":"367659-coronavirus-riprendono-le-crociere-tamponi-e-nuovi-protocolli-di-sicurezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/367659-coronavirus-riprendono-le-crociere-tamponi-e-nuovi-protocolli-di-sicurezza\/","title":{"rendered":"Coronavirus: riprendono le crociere, tamponi e nuovi protocolli di sicurezza"},"content":{"rendered":"<h4>Riprendono le crociere e MSC Grandiosa, \u00e8 la prima nave a partire da uno scalo italiano dopo il lungo stop, salpando dal porto di Genova<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>Si tratta di un evento di profondo significato emozionale &#8211; spiegano dalla compagnia &#8211; per la possibilit\u00e0 di tornare a viaggiare in sicurezza fra le citt\u00e0 pi\u00f9 belle del Mediterraneo, di grande rilevo economico, per la ripresa di un settore cruciale per la blue economy italiana, ma anche di straordinario valore tecnico, per lo sforzo congiunto di tutti gli attori pubblici e privati che hanno consentito di superare le notevoli difficolt\u00e0 per garantire l&#8217;assoluta sicurezza di turisti e personale. MSC Crociere si \u00e8 impegnata a tutelare la sicurezza e la salute degli ospiti in ogni momento del viaggio: dalla prenotazione al tragitto verso la nave, dall&#8217;imbarco alla vita di bordo, dalle escursioni a terra al ritorno a casa.<\/p>\n<p>A tal fine la Compagnia ha messo a punto, con il supporto di un team di esperti internazionali, un rigoroso protocollo che prevede l&#8217;adozione di misure ulteriormente rafforzate rispetto alle linee guida gi\u00e0 rigorose approvate dal Comitato tecnico-scientifico, tra cui: screening medico e test universale Covid-19 per tutti gli ospiti e per l&#8217;equipaggio prima di ogni imbarco; escursioni &#8220;protette&#8221; organizzate dalla Compagnia esclusivamente per i propri ospiti; maggior distanziamento fisico a bordo grazie ad una capienza ridotta della nave; infine, un servizio sanitario di bordo ulteriormente potenziato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riprendono le crociere e MSC Grandiosa, \u00e8 la prima nave a partire da uno scalo italiano dopo il lungo stop, salpando dal porto di Genova<\/p>\n","protected":false},"author":56,"featured_media":135193,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[681],"class_list":["post-135192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=135192"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/135193"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=135192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=135192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=135192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}