{"id":135300,"date":"2020-08-20T07:41:49","date_gmt":"2020-08-20T05:41:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragedia-sfiorata-nella-notte-a-san-lucido-grave-incidente-sulla-statale-18\/"},"modified":"2023-01-16T18:04:58","modified_gmt":"2023-01-16T17:04:58","slug":"367925-tragedia-sfiorata-nella-notte-a-san-lucido-grave-incidente-sulla-statale-18","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/367925-tragedia-sfiorata-nella-notte-a-san-lucido-grave-incidente-sulla-statale-18\/","title":{"rendered":"Tragedia sfiorata nella notte a San Lucido, grave incidente sulla Statale 18"},"content":{"rendered":"<h4>Due auto hanno impattato violentemente nella notte sulla Statale 18 tirrenica, nel territorio di San Lucido. L&#8217;incidente ha provocato notevoli disagi al traffico <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN LUCIDO (CS) &#8211; Un incidente stradale ha coinvolto nella notte due auto, sulla Statale 18 Tirrena inferiore nel territorio del comune di San Lucido. Al momento non \u00e8 chiara la dinamica dell&#8217;impatto, avvenuto intorno all&#8217;una, che ha provocato il blocco della Statale per alcune ore. Secondo quanto si \u00e8 appreso, a bordo delle auto rispettivamente <strong>una famiglia con due bambini<\/strong> e nell&#8217;altra una coppia. Ad avere la peggio uno dei bambini che si trova ricoverato in ospedale a Cosenza con un quadro clinico complesso. Feriti anche tutti gli altri occupanti delle vetture. Sul posto le forze dell&#8217;ordine per i rilievi, i vigili del fuoco e i sanitari del 118. Dopo gli immediati soccorsi i feriti sono stati trasferiti negli ospedali di Paola e Cosenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-367931 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/08\/incidente-san-lucido-notte-19-agosto-.jpg\" alt=\"\" width=\"607\" height=\"386\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due auto hanno impattato violentemente nella notte sulla Statale 18 tirrenica, nel territorio di San Lucido. L&#8217;incidente ha provocato notevoli disagi al traffico<\/p>\n","protected":false},"author":42,"featured_media":135301,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-135300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=135300"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/135301"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=135300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=135300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=135300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}