{"id":135428,"date":"2020-08-22T14:43:20","date_gmt":"2020-08-22T12:43:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/strada-della-morte-dopo-giorni-in-ospedale-muore-un-sedicenne\/"},"modified":"2023-01-16T18:05:08","modified_gmt":"2023-01-16T17:05:08","slug":"368256-strada-della-morte-dopo-giorni-in-ospedale-muore-un-sedicenne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/368256-strada-della-morte-dopo-giorni-in-ospedale-muore-un-sedicenne\/","title":{"rendered":"&#8220;Strada della morte&#8221;, dopo giorni in ospedale muore un ragazzo di 16 anni"},"content":{"rendered":"<h4>Aveva solo 16 anni Cesare, deceduto dopo giorni di ricovero in ospedale dopo l&#8217;incidente avvenuto il 16 agosto scorso sulla strada statale 106 jonica a Corigliano Rossano <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Non ce l&#8217;ha fatta il giovane <strong>Cesare Smurra di 16 anni<\/strong>, dopo giorni in ospedale a lottare tra la vita e la morte a seguito del tragico scontro avvenuto nella notte del <strong>16 agosto scorso sulla strada Statale 106<\/strong>, nel comune di Corigliano Rossano, in provincia di Cosenza. La comunit\u00e0 di Corigliano Rossano &#8211; fa sapere l&#8217;Associazione &#8220;Basta Vittime sulla 106&#8221; &#8211; \u00e8 distrutta dalla tragica scomparsa di Cesare, descritto da tutti come un ragazzo sempre disponibile, gentile, molto educato, amato e stimato. <strong>Cesare ha lottato per rimanere in vita ma purtroppo non ce l\u2019ha fatta.<\/strong><\/p>\n<p>La &#8220;strada della morte&#8221; dunque, fa registrare la <strong>nona vittima<\/strong> dopo Leonardo Guarino di 23 anni deceduto il 16 gosto e Valentino Joseph Buonfino di 24 anni deceduto il 31 luglio entrambi in un incidente avvenuto a Montegiordano (Cs); Salvatore Fiumara di 62 anni e Luigi Peluso di 31 anni, deceduti il 29 luglio a Cropani (Cz), Giacomo Capalbo di 36 anni, deceduto a Mandatoriccio (Cs), il 14 giugno, Thomas Costanzo di 19 anni, deceduto a Borgia (Cz), il 12 gennaio, Salvatore Mario Orlando di 54 anni, deceduto a Bova Marina (Rc), il 18 gennaio e Alessandro Luppino di 15 anni, deceduto a Casignana (Rc).<\/p>\n<p>Colpisce che<strong> su 9 vittime, quest&#8217;anno, ben 7 sono giovani<\/strong>: 3 vittime hanno meno di 20 anni; 2 vittime hanno un&#8217;et\u00e0 compresa tra 23 e 24 anni; 2 vittime hanno un&#8217;et\u00e0 compresa tra 31 e 36 anni. In pratica il 78% delle vittime della S.S.106 nel 2020 sono giovani: mai un dato cos\u00ec alto negli ultimi 10 anni. L&#8217;Associazione intende ribadire e sottolineare che tutto ci\u00f2 rappresenta la pi\u00f9 grande Strage di Stato della storia della Repubblica italiana ed intende evidenziare, inoltre, che quanto accade purtroppo da sempre sulla strada Statale 106 &#8220;Jonica&#8221; in Calabria ha delle chiare ed evidenti responsabilit\u00e0 politiche.<\/p>\n<p>&#8220;Il dibattito surreale e vergognoso sulla realizzazione del <strong>Ponte sullo Stretto<\/strong> ritenuto addirittura &#8220;una priorit\u00e0 infrastrutturale per la Calabria&#8221; \u00e8 una offesa alla memoria di tutte le vittime della strada Statale 106 e si somma al silenzio ed all&#8217;indifferenza del Governo nazionale e regionale, della classe parlamentare calabrese a Roma, delle amministrazioni locali e provinciali, delle forze sindacali. Tutti, nessuno escluso, coloro i quali rivestono ruoli istituzionali, sono moralmente responsabili dell&#8217;olocausto sulla S.S.106. L&#8217;Associazione &#8220;Basta Vittime Sulla Strada Statale 106&#8221; si stringe attorno alla Famiglia della vittima, ai parenti ed agli amici tutti, all&#8217;intera comunit\u00e0 di Corigliano Rossano a cui esprimiamo sentimenti di vicinanza e cordoglio. <strong>Noi non dimenticheremo queste vite spezzate sull&#8217;asfalto<\/strong> della &#8220;<strong>strada pi\u00f9 pericolosa d&#8217;Italia&#8221;.<\/strong> Noi rivendichiamo investimenti sulla strada Statale 106 affinch\u00e9 venga ammodernata perch\u00e9 costituisce da sempre l&#8217;unica priorit\u00e0 infrastrutturale per la Calabria dal momento che sull&#8217;asfalto letale della &#8220;strada della morte&#8221; continua la strage di vite umane! Noi non resteremo indifferenti ed in silenzio davanti all&#8217;ennesima tragedia di una strada sempre pi\u00f9 serial killer in Calabria ed in Italia. La &#8220;strada della morte&#8221;, non ci stancheremo mai di ripeterlo, rappresenta la pi\u00f9 grande Strage di Stato della storia della Repubblica italiana&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aveva solo 16 anni Cesare, deceduto dopo giorni di ricovero in ospedale dopo l&#8217;incidente avvenuto il 16 agosto scorso sulla strada statale 106 jonica a Corigliano Rossano<\/p>\n","protected":false},"author":42,"featured_media":135429,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-135428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=135428"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/135429"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=135428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=135428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=135428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}