{"id":135688,"date":"2020-08-27T16:10:34","date_gmt":"2020-08-27T14:10:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-rossano-positivo-al-covid-il-consigliere-raffaele-vulcano-sto-bene\/"},"modified":"2023-01-16T18:05:25","modified_gmt":"2023-01-16T17:05:25","slug":"369036-corigliano-rossano-positivo-al-covid-il-consigliere-raffaele-vulcano-sto-bene","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/369036-corigliano-rossano-positivo-al-covid-il-consigliere-raffaele-vulcano-sto-bene\/","title":{"rendered":"Corigliano-Rossano, positivo al covid il consigliere Raffaele Vulcano &#8220;sto bene&#8221;"},"content":{"rendered":"<h4>Lo stesso Vulcano ne ha dato notizia con un post sulla sua pagina Facebook &#8220;vorrei rassicurare tutti gli amici sul mio stato di salute. Sto bene ed attualmente sono in isolamento domiciliare <span class=\"text_exposed_show\">per come concordato con la locale ASP&#8221;<\/span><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\nCORIGLIANO &#8211; ROSSANO &#8211; Nuovo caso di coronavirus a Corigliano-Rossano. Non si tratta della persona tornata in autobus da Roma. A tal proposito la task force \u00e8 al lavoro per rintracciare i passeggeri che hanno viaggiato con l\u2019uomo, ma del consigliere comunale Raffaele Vulcano <strong>risultato positivo al Covid e si trova in isolamento domiciliare ed \u00e8 asintomatico<\/strong>. Lo stesso Vulcano, in quota all&#8217;UDC e subentrato a Giuseppe Graziano, ne ha dato notizia sulla sua pagina Facebook &#8220;ho contratto il Covid, vorrei rassicurare tutti gli amici che in questo momento numerosi mi stanno contattando sul mio stato di salute. S<strong>to bene ed attualmente sono in isolamento domiciliare<\/strong> <span class=\"text_exposed_show\">per come concordato con la locale ASP, gi\u00e0 da stamattina i diretti contatti riconducibili alla mia persona si sono sottoposti, come da protocollo, all\u2019esecuzione di tamponi presso i locali dell\u2019Asp ci\u00f2 al fine di mappare al meglio la situazione. <strong>Spero tutto questo possa finire nel minor tempo possibile<\/strong>. Nel frattempo raccomando a tutti prudenza ed il fondamentale rispetto delle regole. Invito altrettanto chiunque \u00e8 venuto in contatto con me di recente a stare tranquilli perch\u00e9 al momento non c\u2019\u00e8 un pericolo di contagio&#8221;. Vulcano <\/span><strong>ha riferito <\/strong>di non aver frequentato locali della movida o luoghi affollati, n\u00e9 \u00e8 stato in vacanza in altre localit\u00e0 ma solo di aver fatto ogni tanto qualche passeggiata e la vita di tutti i giorni.<\/p>\n<p><span class=\"text_exposed_show\"><strong>Il sindaco Flavio Stasi<\/strong> ha mandato un messaggio di sostegno con un &#8220;<strong>i<\/strong><\/span><strong>n bocca al lupo per una veloce guarigione, forza Raf!<\/strong>&#8221;\u00a0 invitando anche lui tutti i cittadini ad una maggiore attenzione ed al rispetto delle basilari norme anti-covid. Intanto il dipartimento prevenzione sta gi\u00e0<strong> effettuando tutte le verifiche necessarie per accertarsi che non ci siano ulteriori contagi.<\/strong><\/p>\n<p><span class=\"text_exposed_show\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo stesso Vulcano ne ha dato notizia con un post sulla sua pagina Facebook &#8220;vorrei rassicurare tutti gli amici sul mio stato di salute. Sto bene ed attualmente sono in isolamento domiciliare per come concordato con la locale ASP&#8221;<\/p>\n","protected":false},"author":55,"featured_media":135689,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-135688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=135688"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/135689"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=135688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=135688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=135688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}