{"id":135776,"date":"2020-08-29T10:58:30","date_gmt":"2020-08-29T08:58:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-positivo-un-calciatore-della-primavera-del-cosenza\/"},"modified":"2023-01-16T18:05:30","modified_gmt":"2023-01-16T17:05:30","slug":"369272-coronavirus-positivo-un-calciatore-della-primavera-del-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/369272-coronavirus-positivo-un-calciatore-della-primavera-del-cosenza\/","title":{"rendered":"Coronavirus, positivo un calciatore della Primavera del Cosenza"},"content":{"rendered":"<h4>Tutti i calciatori nei giorni scorsi sono stati sottoposti al test rino faringeo. Un giocatore della Primavera del Cosenza \u00e8 risultato positivo al Covid 19<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La comunicazione arriva dalla societ\u00e0 rossoblu: &#8220;con il coordinamento dello staff sanitario, i componenti del gruppo squadra presenti in citt\u00e0 si sono sottoposti, nei giorni scorsi, al test molecolare (tampone naso faringeo) per la ricerca del Covid-19. Il ciclo di tamponi \u00e8 stato effettuato in regime di pre raduno garantendo ai tesserati il distanziamento e, in attesa dei risultati, non \u00e8 stata svolta alcuna attivit\u00e0 atletica&#8221;.<\/p>\n<p>&#8220;Le risultanze dei test &#8211; scrive la societ\u00e0 Cosenza Calcio &#8211; sono state comunicate in queste ore e <strong>hanno dato esito negativo per tutti i soggetti interessati<\/strong> tranne che per un <strong>tesserato del settore giovanile<\/strong> per il quale \u00e8 stata riscontrata la <strong>positivit\u00e0<\/strong>. Il giovane calciatore \u00e8 <strong>completamente asintomatico<\/strong> e secondo i protocolli sanitari in vigore, si trova in isolamento, sotto la supervisione dello staff medico societario in stretta collaborazione con l\u2019Autorit\u00e0 Sanitaria locale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutti i calciatori nei giorni scorsi sono stati sottoposti al test rino faringeo. Un giocatore della Primavera del Cosenza \u00e8 risultato positivo al Covid 19<\/p>\n","protected":false},"author":24,"featured_media":135777,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[681],"class_list":["post-135776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=135776"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/135776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/135777"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=135776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=135776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=135776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}