{"id":136044,"date":"2020-09-03T08:53:36","date_gmt":"2020-09-03T06:53:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-centro-di-neuropsichiatria-da-san-lucido-a-fuscaldo-bevacqua-chiede-chiarimenti\/"},"modified":"2023-01-16T18:05:49","modified_gmt":"2023-01-16T17:05:49","slug":"369975-il-centro-di-neuropsichiatria-da-san-lucido-a-fuscaldo-bevacqua-chiede-chiarimenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/369975-il-centro-di-neuropsichiatria-da-san-lucido-a-fuscaldo-bevacqua-chiede-chiarimenti\/","title":{"rendered":"Centro Neuropsichiatria infantile da San Lucido a Fuscaldo, Bevacqua: &#8220;chiarimenti&#8221;"},"content":{"rendered":"<h4>Sullo spostamento del Centro di Neuropsichiatria a Fuscaldo deciso dall&#8217;Asp di Cosenza, il consigliere regionale Domenico Bevacqua chiede chiarimenti e risposte<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN LUCIDO (CS) &#8211; La vicenda del Centro di Neuropsichiatria Infantile di San Lucido necessita di spiegazioni immediate. A chiederle \u00e8 il capogruppo Pd in Consiglio regionale, Domenico Bevacqua. &#8220;Qualora fossero rispondenti a verit\u00e0 le notizie di uno spostamento della struttura a Fuscaldo, bisogna chiarire<strong> le ragioni per cui l&#8217;Asp di Cosenza intenderebbe operare in tal senso&#8221;.<\/strong><\/p>\n<p>Bevacqua ha annunciato la presentazione di un&#8217;interrogazione alla presidente Santelli e al dirigente generale del Dipartimento Salute, Bevere, affinch\u00e9 si faccia <strong>pubblicamente luce <\/strong>su episodi che non possono passare sotto silenzio. <strong>Trenta e pi\u00f9 anni di competenze acquisite<\/strong> &#8211; prosegue Bevacqua &#8211; rischiano di andare disperse&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-98693 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2016\/07\/bevacqua.jpg\" alt=\"bevacqua\" width=\"481\" height=\"261\" title=\"\"><\/p>\n<p>&#8220;Il Centro, operando in ambito di <strong>neuroriabilitazione di bimbi e ragazzi diversamente abili in et\u00e0 scolare,<\/strong> ha efficacemente garantito <strong>servizi di eccellenza per il Tirreno cosentino<\/strong>, attraverso l&#8217;opera costante di un ampio ventaglio di figure professionali, tra cui neuropsichiatri infantili, psicologi psicoterapeuti, logopedisti, fisioterapisti, assistenti sociali. Sarebbe <strong>davvero grave<\/strong> se l&#8217;Asp dovesse smantellare qualcosa che funziona bene e privare le comunit\u00e0 interessate di servizi tanto importanti e delicati&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sullo spostamento del Centro di Neuropsichiatria a Fuscaldo deciso dall&#8217;Asp di Cosenza, il consigliere regionale Domenico Bevacqua chiede chiarimenti e risposte<\/p>\n","protected":false},"author":42,"featured_media":136045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-136044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136044"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136045"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}