{"id":136158,"date":"2020-09-04T15:00:00","date_gmt":"2020-09-04T13:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scuola-congedi-o-smart-working-a-genitori-di-under-14-in-quarantena\/"},"modified":"2023-01-16T18:05:57","modified_gmt":"2023-01-16T17:05:57","slug":"370236-scuola-congedi-o-smart-working-a-genitori-di-under-14-in-quarantena","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/370236-scuola-congedi-o-smart-working-a-genitori-di-under-14-in-quarantena\/","title":{"rendered":"Scuola, congedi o smart working a genitori di under 14 in quarantena"},"content":{"rendered":"<h4>E&#8217; quanto si legge nella nota di Palazzo Chigi sul decreto varato dal Cdm che contiene anche misure fiscali per i lampedusani<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Nel decreto approvato ieri dal Cdm per le misure anti-Covid in vista della ripresa dell&#8217;anno scolastico &#8220;<strong>sono previste misure in materia di smart working e congedi straordinari per i genitori di figli minori di quattordici anni nei casi di quarantena<\/strong> obbligatoria dei figli&#8221;. E&#8217; quanto si legge nella nota di Palazzo Chigi dopo il Cdm. Via libera anche alle misure fiscali per i lampedusani nel decreto sugli ulteriori interventi anti-Covid in vista della ripresa della scuola. Il testo prevede che coloro che &#8220;<strong>hanno il domicilio fiscale, la sede legale o la sede operativa nel territorio del Comune di Lampedusa e Linosa, la sospensione fino al 21 dicembre 2020 dei versamenti dei tributi<\/strong> nonch\u00e9 dei contributi previdenziali ed assistenziali e dei premi per l&#8217;assicurazione obbligatoria contro gli infortuni e le malattie professionali&#8221;.<\/p>\n<p>Nel decreto sono contenute norme &#8220;semplificano l&#8217;assegnazione delle risorse per il rifinanziamento di interventi urgenti in materia di sicurezza per l&#8217;edilizia scolastica stanziate con il decreto-legge 26 ottobre 2019, n. 124, che, per <strong>un ammontare complessivo pari a euro 25 milioni, vengono destinate a supportare gli enti locali in interventi urgenti<\/strong> per lavori finalizzati, in particolare, all&#8217;adeguamento e all&#8217;adattamento a fini didattici degli ambienti e degli spazi, anche assunti in locazione&#8221;. E&#8217; quanto si legge nella nota di Palazzo Chigi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; quanto si legge nella nota di Palazzo Chigi sul decreto varato dal Cdm che contiene anche misure fiscali per i lampedusani<\/p>\n","protected":false},"author":22,"featured_media":136159,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-136158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136158"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136159"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}