{"id":136272,"date":"2020-09-13T14:30:08","date_gmt":"2020-09-13T12:30:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/valutazione-del-rischio-chimico-nuovo-master-allunical-per-formare-professionisti-della-sicurezza\/"},"modified":"2023-01-16T18:06:05","modified_gmt":"2023-01-16T17:06:05","slug":"370554-valutazione-del-rischio-chimico-nuovo-master-allunical-per-formare-professionisti-della-sicurezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/370554-valutazione-del-rischio-chimico-nuovo-master-allunical-per-formare-professionisti-della-sicurezza\/","title":{"rendered":"Valutazione del rischio chimico: nuovo Master all&#8217;Unical per formare professionisti della sicurezza"},"content":{"rendered":"<h4>La figura professionale \u00e8 obbligatoria in tutte le aziende che fabbricano, importano, vendono e usano sostanze chimiche per gestire i rischi collegati alle sostanze stesse<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ARCAVACATA (CS) &#8211; L\u2019Universit\u00e0 della Calabria attiva il <strong>Master di II Livello \u201cValutazione del Rischio Chimico,<\/strong> REACH (Registration, Evaluation, Authorisation and restriction of Chemicals) e CLP (Classification, Labelling, Packaging)\u201d, proposto dal Dipartimento di Chimica e Tecnologie Chimiche in collaborazione con l\u2019Autorit\u00e0 Regionale Competente REACH-CLP-BPR (Dipartimento Tutela Salute e Politiche Sanitarie della Regione Calabria). <strong>Il Master \u00e8 presentato con il supporto del Ministero della Salute e ha come principale obiettivo la formazione di figure professionali<\/strong> con competenze altamente specifiche per l\u2019adeguata applicazione del regolamento REACH e di tutte le normative europee e nazionali ad esso collegate o ad esso riconducibili. Il regolamento REACH \u00e8 un\u2019ampia normativa europea che obbliga le aziende che fabbricano, importano, vendono e usano sostanze chimiche a gestire i rischi collegati alle sostanze stesse.<\/p>\n<p>In questo contesto, i partecipanti al Master acquisiranno le <strong>competenze per operare nelle industrie produttrici, importatrici e utilizzatrici di sostanze chimiche, miscele e articoli,<\/strong> nelle organizzazioni pubbliche preposte all\u2019attuazione e alla vigilanza della normativa sull\u2019argomento, oltre che nelle societ\u00e0 di consulenza chimica e ambientale, garantendo conoscenze e impieghi sempre pi\u00f9 sicuri delle sostanze chimiche nel comune e costante obiettivo di salvaguardia della salute dell\u2019uomo, dell\u2019ambiente e di tutela dei consumatori. <strong>I settori produttivi interessati all\u2019applicazione del Regolamento REACH sono molteplici<\/strong> perch\u00e9, oltre alle aziende che producono direttamente sostanze chimiche, vedono coinvolte anche aziende che utilizzano, ad un certo punto della propria filiera, sostanze chimiche per la produzione di articoli di largo consumo come, per esempio, detergenti e prodotti per la pulizia, calzature, pelli e cuoio, materiali per l\u2019edilizia, gomme, plastiche, pitture e vernici, tessuti per abbigliamento.<\/p>\n<p>Nel presente scenario, <strong>la figura professionale con specifica formazione universitaria sul regolamento REACH che il Master intende formare pu\u00f2 trovare impiego in numerosissime aziende<\/strong> per l&#8217;appropriata applicazione dei regolamenti comunitari nell\u2019ambito della gestione delle sostanze chimiche. Le attivit\u00e0 formative del Master prevedono il <strong>coinvolgimento di esperti nazionali di comprovata esperienza nei diversi settori della prevenzione,<\/strong> alcuni dei quali in attivit\u00e0 presso il Ministero della Salute, l\u2019Istituto Superiore di Sanit\u00e0 e l\u2019Istituto Superiore per la Protezione e la Ricerca Ambientale. Al termine dell\u2019attivit\u00e0 d\u2019aula \u00e8 previsto un periodo di stage presso aziende o enti. Qualora lo studente scelga di espletare il tirocinio presso Strutture dislocate fuori la Regione Calabria, le spese saranno cofinanziate dal Dipartimento di Chimica e Tecnologie Chimiche, nell\u2019ambito dell\u2019accordo di collaborazione con il Ministero della Salute. <strong>Il Bando \u00e8 disponibile a questo link<\/strong> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/11212\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.unical.it\/portale\/portaltemplates\/view\/view.cfm?101511<\/a> <\/span>o sul portale dell\u2019Unical, Dipartimento di Chimica. <strong>La Regione Calabria sostiene la partecipazione a Master attraverso la copertura dei costi d\u2019iscrizione.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La figura professionale \u00e8 obbligatoria in tutte le aziende che fabbricano, importano, vendono e usano sostanze chimiche per gestire i rischi collegati alle sostanze stesse<\/p>\n","protected":false},"author":22,"featured_media":136273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-136272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136272"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136273"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}