{"id":136304,"date":"2020-09-08T07:12:04","date_gmt":"2020-09-08T05:12:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/escursionisti-si-perdono-nei-boschi-del-cupone-ritrovati-dal-soccorso-alpino\/"},"modified":"2023-01-16T18:06:07","modified_gmt":"2023-01-16T17:06:07","slug":"370630-escursionisti-si-perdono-nei-boschi-del-cupone-ritrovati-dal-soccorso-alpino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/370630-escursionisti-si-perdono-nei-boschi-del-cupone-ritrovati-dal-soccorso-alpino\/","title":{"rendered":"Escursionisti si perdono nei boschi del Cupone, ritrovati dal Soccorso alpino"},"content":{"rendered":"<h4>Il ritrovamento \u00e8 stato possibile grazie al sistema di di geolocalizzazione SMS Locator. Le ricerche erano partite dopo che i tre escursionisti hanno allertato il 118<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SPEZZANO DELLA SILA (CS) &#8211; Tre escursionisti siciliani, nel tardo pomeriggio di ieri, hanno chiamato il 118 dopo aver perso il sentiero nei boschi del Cupone nel Parco Nazionale della Sila. Il Soccorso Alpino e Speleologico Calabria, allertato dalla centrale operativa del 118, ha attivato il sistema di geolocalizzazione SMS LOCATOR, che ha permesso, dopo pochi minuti, di ottenere le coordinate dei dispersi. Immediatamente una squadra della Stazione Camigliatello del Soccorso Alpino Calabria \u00e8 giunta sul posto e ha rintracciato i tre escursionisti riportandoli alle loro autovetture.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ritrovamento \u00e8 stato possibile grazie al sistema di di geolocalizzazione SMS Locator. Le ricerche erano partite dopo che i tre escursionisti hanno allertato il 118<\/p>\n","protected":false},"author":42,"featured_media":136305,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-136304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136304"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136305"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}