{"id":136381,"date":"2020-09-11T08:30:11","date_gmt":"2020-09-11T06:30:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/torna-kino-guarimba-amantea-si-trasforma-in-un-set-per-cineasti-e-videomaker\/"},"modified":"2023-01-16T18:06:12","modified_gmt":"2023-01-16T17:06:12","slug":"370837-torna-kino-guarimba-amantea-si-trasforma-in-un-set-per-cineasti-e-videomaker","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/370837-torna-kino-guarimba-amantea-si-trasforma-in-un-set-per-cineasti-e-videomaker\/","title":{"rendered":"Torna Kino Guarimba, Amantea si trasforma in un set per cineasti e videomaker"},"content":{"rendered":"<h4>Fino al 21 settembre, venticinque artisti stranieri ospiti della cittadina tirrenica. Kino Guarimba \u00e8 la residenza creativa dedicata a cineasti e videomaker che trasforma Amantea in un vero e proprio set<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>AMANTEA (CS) &#8211; La 5^ edizione di Kino Guarimba resiste alla pandemia. Il progetto parte della rassegna itinerante di CinemAmbulante che quest\u2019anno si svolger\u00e0 esclusivamente ad Amantea. \u00abPensiamo che la cultura abbia il diritto di ripartire \u2013 commenta il direttore artistico Giulio Vita \u2013 e noi come operatori culturali abbiamo il dovere di creare proposte che rispettino le regole, ma anche quello ripensare e programmare per garantire continuit\u00e0 all\u2019offerta culturale della nostra regione\u00bb.<\/p>\n<p>Dal 10 al 21 settembre Kino Guarimba far\u00e0 di Amantea set sperimentale all\u2019aperto per 25 artisti \u2013 avrebbero dovuto essere 100 ma per motivi di sicurezza ne \u00e8 stato selezionato un numero contenuto \u2013 in rappresentanza di tutti i continenti: <strong>Australia, Austria, Belgio, Inghilterra, Irlanda, Francia, Germania, Italia, Paesi Bassi, Per\u00f9, Polonia, Lituania, Vietnam e la Lituania<\/strong> grazie al contributo dell&#8217;Ambasciata della Lituania.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-370841 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/09\/Kino-guarimba-amantea-02.jpg\" alt=\"\" width=\"496\" height=\"308\" title=\"\"><\/p>\n<p>I weekend con una serata speciale luned\u00ec 21 settembre, saranno dedicati alle proiezioni di CinemAmbulante, quest\u2019anno ospitate tutte in spiaggia, al Lido Azzurro di Amantea. Senza perdere il filo della mutliculturalit\u00e0 che da sempre lo contraddistingue, CinemAmabulante presenter\u00e0 una selezione di cortometraggi che gettano uno sguardo lucido e trasversale sulla socialit\u00e0, l\u2019integrazione, la globalizzazione, la moda, l\u2019identit\u00e0. Una multiculturalit\u00e0 che quest\u2019anno, attraverso le illustrazioni realizzate per l\u2019evento da Sara Fratini, illustratrice e co-direttrice de La Guarimba, mette in connessione i Sud del mondo attraverso la tradizione delle maschere: dalla Calabria con la maschera apotropaica di Seminara, al Sud America con quella dei Piaroa &#8211; popolo indigeno nomade che vive sulle rive dell\u2019Orinoco -, passando per la grande tradizione delle maschere del continente africano.<\/p>\n<p>Ancora una volta Amantea diventa, attraverso la settima arte, centro vitale di confronto tra culture, protagonista di un vero e laboratorio creativo che accoglier\u00e0 con Kino Guarimba attori, attrici, registi e tecnici del cinema. Una residenza che, attraverso la realizzazione di corti coprodotti da La Guarimba, racconter\u00e0 la piccola cittadina sul tirreno con sguardi inediti. I lavori prodotti verranno presentati luned\u00ec 21 settembre nella serata finale di CinemAmbulante.<\/p>\n<h3>Il Programma<\/h3>\n<h4>Venerd\u00ec 11 settembre alle 21:00<\/h4>\n<p>L\u2019ELEFANTE NELLA STANZA di Kartik Singh (Francia\/Italia)<br \/>\nQuando Rita scopre di avere poco tempo da vivere, la sua preoccupazione principale non \u00e8 morire. Invece, \u00e8 sopraffatta dalla preoccupazione per suo figlio Gianni, che ha un cuore d\u2019oro ma \u00e8 socialmente impacciato e vive ancora a casa. Rita chiede aiuto a Daniela, una nuova arrivata in citt\u00e0 che ha recentemente divorziato e ha giurato dimenticare del tutto gli uomini. Daniela accetta di diventare una insegnante per gli appuntamenti galanti di Gianni, ed \u00e8 cos\u00ec che le cose si complicano.<\/p>\n<h4>Sabato 12\u00a0settembre alle 21:00<\/h4>\n<p>SELEZIONE DI CORTOMETRAGGI<br \/>\nCinemAmbulante propone una selezione di cortometraggi che riflettono lo spirito del progetto: PLAYGROUND ADDICTION dimostra come lo sport possa essere uno strumento per l\u2019integrazione; PUPONE mostra la vita dentro le Case Famiglia italiane; SCHIAVONEA \u00e8 una storia calabrese di migranti e mafia; In ONE STEP CLOSER seguiamo una famiglia curda mentre fa amicizia con i suoi vicini sloveni.<\/p>\n<h4>Domenica 13 settembre alle 21:00<\/h4>\n<p>WAX IN THE CITY di Elie S\u00e9onnet (Francia)<br \/>\nL\u2019Africa \u00e8 alla moda! Il suo simbolo? Le stampe wax! Che sempre pi\u00f9 fashion designer stanno usando nelle loro creazioni. Flora Coquerel, Miss France 2014, con un background franco-beninese, ti invita a seguirli nella loro vita frenetica e globalizzata.<\/p>\n<h4>Sabato 19 settembre alle 21:00<\/h4>\n<p>REVOLUTION FROM AFAR di Bentley Brown (Stati Uniti)<br \/>\nPoeti e musicisti americano-sudanensi si impegnano in performance e conversazioni a proposito della loro identit\u00e0 culturale e della rivoluzione in Sudan, da cui sono stati tagliati fuori fisicamente.<\/p>\n<h4>Domenica 20 settembre alle 21:00<\/h4>\n<p>BARACOA di Pablo Briones (Svizzera)<br \/>\nQuando l\u2019estate arriva nel loro piccolo paese delle campagne cubane, Leonel e Antu\u00e1n esplorano intimamente il loro universo cos\u00ec lontano dagli adulti. Con una differenza considerevole nell\u2019et\u00e0, la loro amicizia unica \u00e8 costruita attorno a giochi e combattimenti, conversazioni sulla vita quotidiana, domande esistenzialiste, semplici piaceri e noia.<\/p>\n<h4>Luned\u00ec 21 \u00a0settembre alle 21:00<\/h4>\n<p>KINO GUARIMBA<br \/>\nIl KINO e\u0300 un un raduno di cineasti e videomakers di tutte le nazionalita\u0300 che sentono il desiderio impellente di creare, rifiutando di seguire la strada della produzione \u201ctradizionale\u201d. Durante questa serata proietteremo i cortometraggi realizzati ad Amantea da questo gruppo di artisti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fino al 21 settembre, venticinque artisti stranieri ospiti della cittadina tirrenica. Kino Guarimba \u00e8 la residenza creativa dedicata a cineasti e videomaker che trasforma Amantea in un vero e proprio set<\/p>\n","protected":false},"author":42,"featured_media":136382,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-136381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136381"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136382"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}