{"id":136439,"date":"2020-09-12T15:00:44","date_gmt":"2020-09-12T13:00:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/wwf-in-50-anni-persa-il-68-di-fauna-selvatica\/"},"modified":"2023-01-16T18:06:16","modified_gmt":"2023-01-16T17:06:16","slug":"371000-wwf-in-50-anni-persa-il-68-di-fauna-selvatica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/371000-wwf-in-50-anni-persa-il-68-di-fauna-selvatica\/","title":{"rendered":"WWF, in 50 anni persa il 68% di fauna selvatica"},"content":{"rendered":"<h4>Il mondo ha perso pi\u00f9 di due terzi della sua popolazione di animali selvatici in meno di 50 anni, principalmente a causa dell&#8217;attivit\u00e0 umana<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Tra il 1970 e il 2016 il 68% di questa fauna \u00e8 scomparso, secondo il Living Planet Index, uno strumento di riferimento pubblicato ogni due anni dal Wwf. <strong>La causa principale \u00e8 la distruzione degli habitat naturali<\/strong>, soprattutto per l&#8217;agricoltura, tendenza che rischia di favorire nuove pandemie di tipo Covid-19: mettendo in contatto uomo e animali si agevola la trasmissione di virus da specie a specie. Questo indice, compilato in collaborazione con la Zoological Society of London, prende in considerazione circa <strong>4.000 specie di vertebrati suddivise in circa 21.000 popolazioni animali in tutto il mondo.<\/strong> Ha registrato una nuova accelerazione nella caduta della biodiversit\u00e0, che si era attestata al 60% durante l&#8217;ultimo rapporto del 2018 (periodo 1970\/2014). &#8220;Per 30 anni abbiamo visto la caduta accelerare e continua nella direzione sbagliata&#8221;, ha detto l&#8217;AFP Marco Lambertini, direttore del Wwf internazionale. &#8220;Stiamo assistendo alla distruzione della natura da parte dell&#8217;umanit\u00e0. In effetti, \u00e8 un ecocidio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il mondo ha perso pi\u00f9 di due terzi della sua popolazione di animali selvatici in meno di 50 anni, principalmente a causa dell&#8217;attivit\u00e0 umana<\/p>\n","protected":false},"author":56,"featured_media":136440,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-136439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136439"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136440"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}