{"id":136441,"date":"2020-09-10T07:26:31","date_gmt":"2020-09-10T05:26:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-pietrapaola-si-torna-alle-urne-respinto-il-ricorso-dellex-sindaco\/"},"modified":"2023-01-16T18:06:16","modified_gmt":"2023-01-16T17:06:16","slug":"371004-a-pietrapaola-si-torna-alle-urne-respinto-il-ricorso-dellex-sindaco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/371004-a-pietrapaola-si-torna-alle-urne-respinto-il-ricorso-dellex-sindaco\/","title":{"rendered":"A Pietrapaola si torna alle urne. Respinto il ricorso dell&#8217;ex sindaco"},"content":{"rendered":"<h4>I giudici del TAR hanno accolto le eccezioni dell\u2019avvocato Oreste Morcavallo, difensore dei due candidati a sindaco e perci\u00f2 a Pietrapaola si andr\u00e0 alle urne il prossimo 20 e 21 settembre<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PIETRAPAOLA (CS) &#8211; Nel piccolo centro jonico cosentino il 20 e 21 settembre si svolgeranno le elezioni per la scelta del nuovo sindaco. Il Tar Calabria (1^ sezione) ha <strong>respinto <\/strong>infatti<strong>, il ricorso proposto dall\u2019ex sindaco<\/strong> contro lo scioglimento del Consiglio comunale, disposto con Decreto del Presidente della Repubblica il 22 luglio 2020. Il Tar ha accolto integralmente le eccezioni svolte dall&#8217;avv. Oreste Morcavallo, difensore dei due candidati a sindaco.<\/p>\n<p><strong>A seguito delle dimissioni di 6 consiglieri del Comune di Pietrapaola<\/strong>, il Prefetto aveva sospeso il Consiglio e rimesso gli atti al Ministero dell&#8217;Interno per la proposta di scioglimento ai sensi dell&#8217;art. 141 T.U.E.L.<br \/>\nIl Ministro degli Interni ha disposto poi lo scioglimento con Decreto del Presidente della Repubblica. L&#8217;ex primo cittadino per\u00f2 aveva presentato ricorso <strong>sostenendo l&#8217;illegittimit\u00e0 del decreto di scioglimento<\/strong> perch\u00e9 era necessario preventivamente provvedere alla surroga di un consigliere dimissionario che avrebbe ricompattato la maggioranza.<\/p>\n<p>Al ricorso <strong>si sono opposti i due candidati a sindaco<\/strong> delle due liste ammesse alle elezioni, difesi dall&#8217;avv. Morcavallo, il quale ha sostenuto che l&#8217;art. 38 T.U.E.L. stabilisce che la surroga deve essere approvata con apposita delibera ed a maggioranza del Consiglio, e, non essendo nella specie stata approvata, le dimissioni ultra dimidium dei consiglieri comportano ipso facto lo scioglimento del Consiglio. IL TAR ha aderito a tale tesi e rigettato il ricorso, <strong>pertanto le elezioni a Pietrapaola possono svolgersi regolarmente.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I giudici del TAR hanno accolto le eccezioni dell\u2019avvocato Oreste Morcavallo, difensore dei due candidati a sindaco e perci\u00f2 a Pietrapaola si andr\u00e0 alle urne il prossimo 20 e 21 settembre<\/p>\n","protected":false},"author":42,"featured_media":136442,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-136441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136441"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136442"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}