{"id":136467,"date":"2020-09-10T13:09:30","date_gmt":"2020-09-10T11:09:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-in-fiamme-un-furgone-nei-pressi-dello-stadio-lorezon-statale-chiusa\/"},"modified":"2023-01-16T18:06:18","modified_gmt":"2023-01-16T17:06:18","slug":"371095-rende-in-fiamme-un-furgone-nei-pressi-dello-stadio-lorezon-statale-chiusa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/371095-rende-in-fiamme-un-furgone-nei-pressi-dello-stadio-lorezon-statale-chiusa\/","title":{"rendered":"FOTO &#8211; VIDEO In fiamme un furgone nei pressi dello stadio Lorenzon. Illesi gli occupanti"},"content":{"rendered":"<h4>Le fiamme, che hanno interessato un camion-frigo andato quasi distrutto, sono state prontamente domante dall&#8217;intervento dei vigili del fuoco. Illesi di occupanti <!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\nRENDE\u00a0 &#8211; Un camion-frigo in transito sulla Strada Statale 107 Silana Crotonese, nei pressi della<strong> rotatoria dello stadio Lorezon di Rende,<\/strong> per cause in corso di accertamento, ha preso improvvisamente fuoco. <strong>Illesi gli occupanti di mezzo<\/strong> che sono riusciti a fermarsi proprio nei pressi della rotonda e a scendere velocemente, mentre la cabina del mezzo (al cui interno vi erano alcune pedane di legno) veniva avvolta dalle fiamme che hanno anche sprigionato una <strong>lunga colonna di fumo nero<\/strong> visibile a chilometri di distanza.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/x0ytSYdnBN8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>Immediato l&#8217;intervento di due mezzi dei vigili del fuoco<\/strong> che sono riusciti prontamente a spegnere le fiamme, che hanno interessato anche della vegetazione ai lati della carreggiata, anche se il mezzo \u00e8 andato quasi totalmente distrutto. La<strong> Statale 107, dopo essere stata momentaneamente chiusa al traffico<\/strong> per permettere le operazioni di spegnimento, \u00e8 stata riaperta.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Le fiamme, che hanno interessato un camion-frigo andato quasi distrutto, sono state prontamente domante dall&#8217;intervento dei vigili del fuoco. Illesi di occupanti<\/p>\n","protected":false},"author":55,"featured_media":136468,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-136467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136467"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136468"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}