{"id":136607,"date":"2020-09-14T08:49:42","date_gmt":"2020-09-14T06:49:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/muore-a-24-mesi-per-un-pacemaker-impiantato-al-contrario-8-medici-indagati\/"},"modified":"2023-01-16T18:06:27","modified_gmt":"2023-01-16T17:06:27","slug":"371448-muore-a-24-mesi-per-un-pacemaker-impiantato-al-contrario-8-medici-indagati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/371448-muore-a-24-mesi-per-un-pacemaker-impiantato-al-contrario-8-medici-indagati\/","title":{"rendered":"Muore a 24 mesi per un pacemaker impiantato al contrario, 8 medici indagati"},"content":{"rendered":"<h4>La morte del bimbo Giacomo Francesco Saccomanno, di 24 mesi, \u00e8 avvenuta il 3 gennaio dello scorso anno presso il Bambin Ges\u00f9 di Roma dopo l&#8217;intervento avvenuto all&#8217;ospedale di Taormina\u00a0 <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Si terr\u00e0 domani davanti al gip di Roma l&#8217;incidente probatorio per la morte di un bimbo di 2 anni, Giacomo Francesco Saccomanno, di Rosarno (Rc), al quale sarebbe stato impiantato un pacemaker al contrario. Poi una serie di presunti errori hanno portato al suo decesso. Giacomo era stato operato nel 2016 a Taormina, subito dopo la nascita, per un&#8217;insufficienza cardiocircolatoria al centro cardiologico pediatrico Mediterraneo dell&#8217;Ospedale Bambino Ges\u00f9 del San Vincenzo di Taormina ma da quel momento \u00e8 iniziato il suo calvario. Nel 2018 \u00e8 stato trasferito d&#8217;urgenza all&#8217;ospedale Bambino Ges\u00f9 di Roma dove poi \u00e8 deceduto a gennaio 2019. Per la sua morte, sono indagati 8 medici che lo hanno avuto in cura, con l&#8217;accusa <strong>di omicidio in cooperazione colposa consistita da negligenza, imprudenza ed imperizia.<\/strong><\/p>\n<p>Il piccolo era nato con un problema al cuore, un &#8220;<strong>blocco atrioventricolare completo congenito<\/strong>&#8220;. Per questo era stato operato a Taormina nel Centro cardiologico pediatrico Mediterraneo del Bambin Ges\u00f9. Ma secondo la perizia di parte i medici avrebbero impiantano il pacemaker al contrario. Un errore che avrebbe provocato un &#8220;cappio con progressivo strangolamento dell&#8217;arteria polmonare ed una compressione dell&#8217;anello mitralico, cos\u00ec concorrendo a cagionare la morte&#8221;.<\/p>\n<p>Per il legale della <strong>famiglia rosarnese<\/strong> la consulenza tecnica di parte ravvisa queste responsabilit\u00e0 mentre la direzione dell&#8217;ospedale aveva replicato definendo &#8220;la ricostruzione della vicenda, lontana dalla realt\u00e0. Non esiste nessun pacemaker \u201cmesso al contrario\u201d. L\u2019affermazione non ha alcun senso dal punto di vista clinico e non trova riscontro negli accertamenti finora effettuati finanche dai consulenti della famiglia. <strong>Vi \u00e8 stata, invece, una complicanza prevista in letteratura che si registra in pochissimi casi e risolvibile chirurgicamente<\/strong>. L\u2019intervento era stato gi\u00e0 programmato. Ma il bambino purtroppo, in attesa di tornare a ricovero, ha contratto un virus e poi una polmonite che gli \u00e8 risultata fatale\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La morte del bimbo Giacomo Francesco Saccomanno, di 24 mesi, \u00e8 avvenuta il 3 gennaio dello scorso anno presso il Bambin Ges\u00f9 di Roma dopo l&#8217;intervento avvenuto all&#8217;ospedale di Taormina\u00a0<\/p>\n","protected":false},"author":42,"featured_media":136608,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-136607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136607"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136608"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}