{"id":136735,"date":"2020-09-20T09:30:00","date_gmt":"2020-09-20T07:30:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/malanni-di-stagione-un-carico-di-vitamine-per-evitarli\/"},"modified":"2023-01-16T18:06:35","modified_gmt":"2023-01-16T17:06:35","slug":"371780-malanni-di-stagione-un-carico-di-vitamine-per-evitarli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/371780-malanni-di-stagione-un-carico-di-vitamine-per-evitarli\/","title":{"rendered":"Malanni di stagione, un carico di vitamine per evitarli"},"content":{"rendered":"<h4>Settembre \u00e8 il mese della ripresa ed entrano in gioco le vitamine, potenti alleate dell\u2019organismo e carte vincenti per ripartire con il piede giusto<\/h4>\n<p><!--more--><\/p>\n<p>Le vitamine hanno numerosi benefici e ci permettono di prenderci cura di noi. La vitamina D ha un effetto benefico su tutto il corpo: aiuta a rinforzare le ossa, regola e protegge il sistema immunitario, migliora l\u2019umore e riduce i rischi associati ad alcune malattie cardiache. Nonostante sia presente in alcuni cibi, come i pesci grassi e le uova, <strong>la principale fonte di vitamina D \u00e8 l\u2019esposizione al sole<\/strong>, perch\u00e9 \u00e8 proprio grazie ai raggi UVB che si forma nella pelle per poi essere assorbita dall\u2019organismo.<\/p>\n<p><strong>Per prendersi cura dei capelli sono fondamentali le vitamine del gruppo B.<\/strong> La B1 e la B8, per esempio, aiutano a regolare il ciclo vitale del capello, la B2 potenzia la sintesi del sebo e la B4 contribuisce a ottimizzare la funzione dei follicoli piliferi. Ultime, ma non meno importanti, la B5, che favorisce la crescita e la B9, che sta alla base della sintesi della cheratina, indispensabile per il benessere di tutta la chioma.<\/p>\n<p>La vitamina E ha importanti propriet\u00e0 antiossidanti in grado di proteggere dai danni prodotti dai radicali liberi e da agenti esterni come fumo, vento e inquinamento. Presente in moltissimi rossetti, questa vitamina aiuta non solo a proteggere le labbra, ma anche a idratarle. Le migliori per il benessere delle unghie sono le vitamine liposolubili, come la A e la E, e le idrosolubili, come la vitamina H. Insieme contribuiscono alla ricostruzione e alla rigenerazione capillare, favoriscono la crescita e combattono la fragilit\u00e0 delle unghie..<\/p>\n<p><strong>La vitamina C \u00e8 importantissima per il benessere di tutto l\u2019organismo<\/strong> e, in particolare, per quello della pelle: stimola la formazione di collagene ed elastina, fondamentali per mantenere la tonicit\u00e0 e combattere i segni del tempo. Questa vitamina, inoltre, \u00e8 un potente antiossidante che aiuta a contrastare i danni causati da fattori esterni, primo fra tutti l\u2019inquinamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Settembre \u00e8 il mese della ripresa ed entrano in gioco le vitamine, potenti alleate dell\u2019organismo e carte vincenti per ripartire con il piede giusto<\/p>\n","protected":false},"author":56,"featured_media":136736,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[52],"tags":[],"class_list":["post-136735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=136735"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/136735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/136736"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=136735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=136735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=136735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}