{"id":137004,"date":"2020-09-21T08:56:55","date_gmt":"2020-09-21T06:56:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fermato-con-leroina-pronta-da-spacciare-nel-quartiere-timpone-rosso-arrestato\/"},"modified":"2023-01-16T18:06:54","modified_gmt":"2023-01-16T17:06:54","slug":"372505-fermato-con-leroina-pronta-da-spacciare-nel-quartiere-timpone-rosso-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/372505-fermato-con-leroina-pronta-da-spacciare-nel-quartiere-timpone-rosso-arrestato\/","title":{"rendered":"Fermato con l&#8217;eroina pronta da spacciare nel quartiere Timpone Rosso, arrestato"},"content":{"rendered":"<h4>Gli uomini del commissariato di Polizia di Corigliano-Rossano, hanno arrestato sabato un 31enne per detenzione e spaccio di eroina<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASSANO ALLO JONIO (CS) &#8211; I sospetti degli agenti del commissariato di Corigliano Rossano, si sono concentrati su alcuni <strong>strani movimenti di diversi assuntori di droga<\/strong> dell\u2019area della Sibaritide. Per questo hanno avviato un monitoraggio dei loro spostamenti al fine di individuare il punto di approvvigionamento. Gli investigatori hanno cos\u00ec ricondotto la base operativa da cui gli assuntori si rifornivano nel territorio di Cassano allo Ionio, ed in particolare il <strong>quartiere \u201cTimpone Rosso\u201d di Lauropoli<\/strong>.<\/p>\n<p>Durante le fasi di tale attivit\u00e0, gli operatori di Polizia, sono riusciti a bloccare tempestivamente un\u2019autovettura in transito condotta da un <strong>giovane V.D.<\/strong> che \u00e8 stato subito perquisito. Addosso aveva tre involucri in cellophane termosaldati con <strong>15 grammi di eroina per un valore di circa 750 euro.<\/strong> La perquisizione \u00e8 stata poi estesa sia all\u2019autovettura che nell\u2019abitazione di V.D. e alla luce degli elementi raccolti \u00e8 stato arrestato e posto agli arresti domiciliari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli uomini del commissariato di Polizia di Corigliano-Rossano, hanno arrestato sabato un 31enne per detenzione e spaccio di eroina<\/p>\n","protected":false},"author":42,"featured_media":137005,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-137004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/137004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=137004"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/137004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/137005"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=137004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=137004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=137004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}